{"id":2499,"date":"2026-01-06T07:05:44","date_gmt":"2026-01-06T07:05:44","guid":{"rendered":"https:\/\/vivotis.com\/?page_id=2499"},"modified":"2026-01-06T08:19:14","modified_gmt":"2026-01-06T08:19:14","slug":"it","status":"publish","type":"page","link":"https:\/\/vivotis.com\/pt\/pedohelp\/it\/","title":{"rendered":"PedoHelp IT"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"lang-dropdown\">\n  <button class=\"lang-current\">\n    <span class=\"flag\">\ud83c\udf10<\/span>\n    <span class=\"label\">L\u00edngua<\/span>\n    <span class=\"arrow\">\u25be<\/span>\n  <\/button>\n\n  <ul class=\"lang-list\">\n    <li><a href=\"https:\/\/pedo.help\/\"><span class=\"flag\">\ud83c\uddec\ud83c\udde7<\/span> Ingl\u00eas<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/fr\/\"><span class=\"flag\">\ud83c\uddeb\ud83c\uddf7<\/span> Franc\u00eas<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/nl\/\"><span class=\"flag\">\ud83c\uddf3\ud83c\uddf1<\/span> Pa\u00edses Baixos<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/de\/\"><span class=\"flag\">\ud83c\udde9\ud83c\uddea<\/span> Alem\u00e3o<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/es\/\"><span class=\"flag\">\ud83c\uddea\ud83c\uddf8<\/span> Espanhol<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/it\/\"><span class=\"flag\">\ud83c\uddee\ud83c\uddf9<\/span> Italiano<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/pt\/\"><span class=\"flag\">\ud83c\uddf5\ud83c\uddf9<\/span> Portugu\u00eas<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/pl\/\"><span class=\"flag\">\ud83c\uddf5\ud83c\uddf1<\/span> Polaco<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ru\/\"><span class=\"flag\">\ud83c\uddf7\ud83c\uddfa<\/span> \u0420\u0443\u0441\u0441\u043a\u0438\u0439<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/tr\/\"><span class=\"flag\">\ud83c\uddf9\ud83c\uddf7<\/span> T\u00fcrk\u00e7e<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ar\/\"><span class=\"flag\">\ud83c\uddf8\ud83c\udde6<\/span> \u0627\u0644\u0639\u0631\u0628\u064a\u0629<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/hi\/\"><span class=\"flag\">\ud83c\uddee\ud83c\uddf3<\/span> \u0939\u093f\u0928\u094d\u0926\u0940<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ja\/\"><span class=\"flag\">\ud83c\uddef\ud83c\uddf5<\/span> \u65e5\u672c\u8a9e<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ko\/\"><span class=\"flag\">\ud83c\uddf0\ud83c\uddf7<\/span> \ud55c\uad6d\uc5b4<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/zh\/\"><span class=\"flag\">\ud83c\udde8\ud83c\uddf3<\/span> \u4e2d\u6587<\/a><\/li>\n  <\/ul>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h4>Offrire comprensione e sostegno per prevenire gli abusi sessuali sui minori<\/h4>\n<h5>Non si scelgono le proprie fantasie<\/h5>\n<p><strong>Si sente attratto dai bambini e teme di poter abusare di un bambino?<\/strong>\u00a0Le vostre fantasie vi rendono infelici? A volte desiderate masturbarvi guardando immagini di bambini? Prima di commettere un atto irreversibile o di imprigionarvi con sentimenti di vergogna,\u00a0<strong>prendetevi il tempo di leggere questa pagina.<\/strong><\/p>\n<h5>Nessuna vergogna, nessun tab\u00f9<\/h5>\n<p>Non siete responsabili delle vostre fantasie, ma siete responsabili di tutte le vostre scelte e di tutte le vostre azioni.<br \/>\nIn molti Paesi esistono professionisti e associazioni che possono aiutare.\u00a0<a href=\"https:\/\/vivotis.com\/it\/pedoaiuto\/#help\"><strong><u>Trova aiuto \u00bb<\/u><\/strong><\/a><\/p>\n<hr \/>\n<h5>Voglio fare sesso con un bambino<\/h5>\n<p>Non lasciatevi ingannare dai vostri desideri:\u00a0<strong>Nessun bambino vuole mai avere rapporti sessuali con un adulto, mai e poi mai.<\/strong>\u00a0Un bambino potrebbe dirvi che vuole avere rapporti sessuali, oppure potrebbe avere paura di dire di no perch\u00e9 vuole compiacervi. Potrebbe sembrare che cerchi un contatto sessuale con voi perch\u00e9 ha vissuto un&#8217;esperienza che lo ha disturbato o turbato. Il vostro obbligo, come adulti o adolescenti, \u00e8 quello di rispondere che le relazioni sessuali o romantiche con i bambini sono proibite perch\u00e9 danneggiano i bambini.<\/p>\n<h5>Sento l&#8217;impulso di masturbarmi guardando immagini di bambini<\/h5>\n<p>Lo sfruttamento di un bambino utilizzando la sua immagine \u00e8 inaccettabile. Non lasciatevi ingannare dal sorriso forzato di un bambino manipolato dagli adulti. Masturbarsi con queste immagini vi rende complici dello sfruttamento sessuale della loro immagine.\u00a0<strong>Il rischio di dipendenza e di isolamento \u00e8 molto concreto.<\/strong><\/p>\n<h5>Vorrei non essere pi\u00f9 attratto dai bambini<\/h5>\n<p>Anche se in questo momento vi sembra di non riuscire a immaginare una vita senza essere attratti dai bambini, sappiate che molte persone sono riuscite a superare o a controllare i loro impulsi con l&#8217;aiuto di uno specialista. Questa attrazione non deve per forza definire tutta la vostra vita.\u00a0<strong>L&#8217;importante \u00e8 non isolarsi con le proprie pulsioni.<\/strong>\u00a0o di intrappolarsi in una fantasia inquietante, o di credere di essere condannati a una vita senza sessualit\u00e0 appagante.<\/p>\n<hr \/>\n<h4>Sulla pedofilia<\/h4>\n<h6>Che cos&#8217;\u00e8 la pedofilia e chi \u00e8 un pedofilo?<\/h6>\n<p>I pedofili possono essere adolescenti o adulti di qualsiasi sesso che si sentono attratti sessualmente da bambini prepuberi (cio\u00e8 che non hanno ancora raggiunto la pubert\u00e0) o da bambini che hanno appena iniziato lo sviluppo puberale. In genere, secondo i criteri diagnostici, si tratta di bambini di et\u00e0 inferiore ai 13 anni.<br \/>\nAlcuni pedofili sono attratti solo dalle ragazze, altri solo dai ragazzi. Alcuni sono attratti da entrambi e altri sono attratti in egual misura da bambini, adolescenti o adulti.<br \/>\nLa pedofilia esiste in tutto il mondo e in tutti i contesti sociali, culturali ed economici. Solo perch\u00e9 nessuno ne parla non significa che non esista!<br \/>\nNessuno sceglie di sperimentare questa attrazione, e\u00a0<strong>la maggior parte dei pedofili non abuser\u00e0 mai di un bambino<\/strong>.<br \/>\nNessuno \u00e8 responsabile dei pensieri indesiderati che compaiono nella sua mente, ma ognuno \u00e8 responsabile delle proprie azioni. \u00c8 severamente vietato qualsiasi comportamento che oltrepassi i confini dell&#8217;intimit\u00e0 o della sessualit\u00e0 con un bambino. Ci\u00f2 include esprimere intenzioni romantiche, fare commenti allusivi, mostrare materiale inappropriato, esporsi o coinvolgere un bambino in qualsiasi forma di comportamento sessuale adulto.<\/p>\n<h6>Perch\u00e9 la pedofilia fa cos\u00ec paura?<\/h6>\n<p>Spesso la pedofilia viene erroneamente definita come l&#8217;atto di abusare sessualmente dei bambini. In realt\u00e0, la pedofilia non \u00e8 un atto ma un&#8217;attrazione sessuale.<br \/>\nLe persone con questa attrazione non sono intrinsecamente pericolose o moralmente difettose. Spesso sono persone che soffrono e che hanno bisogno di aiuto per affrontare i loro pensieri o per vivere le loro fantasie senza aggredire effettivamente un bambino.<\/p>\n<h6>Perch\u00e9 si diventa pedofili?<\/h6>\n<p>Le ragioni sono molteplici e dipendono dalla storia personale di ciascun individuo. Alcuni pedofili hanno subito violenze durante l&#8217;infanzia, che possono essere state o meno di natura sessuale. Altri sono stati profondamente disturbati nel periodo in cui stavano esplorando la propria sessualit\u00e0, e altri ancora potrebbero essere cresciuti in famiglie in cui i confini dell&#8217;intimit\u00e0 erano poco chiari o mal definiti.<\/p>\n<h6>Pedofilo una volta, pedofilo per sempre?<\/h6>\n<p>Sperimentare questa attrazione pu\u00f2 essere profondamente angosciante, ma non \u00e8 una condanna a vita. Alcune persone non si sentono pi\u00f9 attratte dai bambini dopo aver ricevuto una terapia o il sostegno di uno specialista. Altri imparano a convivere con queste fantasie senza sentirsi invasi dalla vita quotidiana.<\/p>\n<h6>\u00c8 vero che un adulto pu\u00f2 provare sentimenti romantici verso un bambino?<\/h6>\n<p>Un adolescente o un adulto pu\u00f2 provare sentimenti d&#8217;amore per un bambino, ma questo non dovrebbe mai portare a una relazione sessuale, perch\u00e9 \u00e8 impossibile condividere l&#8217;amore e il desiderio sessuale con i bambini. Questo perch\u00e9 i bambini non sono ancora abbastanza maturi per capire questo tipo di cose e una relazione sessuale \u00e8 sempre dannosa per un bambino, anche quando c&#8217;\u00e8 tenerezza, amore e dolcezza. Quando una persona pubescente prova desiderio sessuale verso una persona prepuberale molto pi\u00f9 giovane, dovrebbe sempre prendere le distanze e cercare aiuto, perch\u00e9 \u00e8 un segno di un problema.<\/p>\n<h6>La societ\u00e0 contribuisce a creare atteggiamenti dannosi quando sessualizza i bambini?<\/h6>\n<p>La nostra societ\u00e0 non dovrebbe n\u00e9 erotizzare i bambini (concorsi di bellezza per bambini, abbigliamento da adulti o trucco pesante su bambini piccoli&#8230;) n\u00e9 infantilizzare gli adulti (forme del corpo prepuberali, assenza di peli sul corpo come standard&#8230;).<br \/>\nLa nostra societ\u00e0 impedisce ai bambini di essere bambini e agli adulti di essere adulti quando cancella le differenze tra le generazioni, causando una grave confusione che a volte pu\u00f2 portare alla violenza sessuale su un bambino.<br \/>\nUna bambina vestita da donna sexy (con abiti attillati, minigonne, pantaloncini corti, bikini&#8230;) pu\u00f2 farci sentire profondamente a disagio; ma se suscita un&#8217;eccitazione sessuale allora bisogna prenderne atto, e bisogna essere consapevoli che sta solo giocando a fingersi adulta e che \u00e8 ancora una bambina. Il suo abbigliamento o il suo comportamento non sono mai un invito o un&#8217;espressione di intenti sessuali.<\/p>\n<h6>C&#8217;\u00e8 il rischio di guardare foto o video di bambini nudi?<\/h6>\n<p>L&#8217;uso di immagini sessualizzate che coinvolgono minori allena il cervello ad associare l&#8217;eccitazione a materiale inappropriato e pu\u00f2 rapidamente degenerare in uno schema compulsivo. Con il passare del tempo, si avr\u00e0 bisogno di vedere un numero sempre maggiore di queste immagini per eccitarsi e, in breve tempo, si sentir\u00e0 il bisogno di vedere immagini di bambini nudi in pose esplicite o che subiscono violenze sessuali.<br \/>\nLa visione di materiale pedopornografico (CSAM) (pornografia infantile, contenuti pedosessuali, pornografia infantile&#8230;) vi rende complici delle aggressioni che questi bambini subiscono durante la produzione di tali immagini o filmati. Quando vedete queste immagini &#8211; anche se non le pagate e non le condividete &#8211; siete coinvolti in un sistema economico che incoraggia la produzione di queste immagini, e quindi di atti aggressivi verso altri bambini.<br \/>\nIn quasi tutti i paesi \u00e8 illegale produrre, distribuire o guardare immagini di pornografia infantile e le pene previste sono severe!<br \/>\nI rischi connessi sono molti: l&#8217;arresto da parte della polizia, l&#8217;assuefazione a queste immagini, l&#8217;incitamento a riprodurre queste aggressioni sui bambini della propria cerchia&#8230;<br \/>\nSe se sentir preso a estas imagens, deve procurar rapidamente a ajuda de um especialista para o ajudar a libertar-se delas. Deve sempre ver as crian\u00e7as nestas imagens pelo que elas s\u00e3o: v\u00edtimas de explora\u00e7\u00e3o que passam por algo traum\u00e1tico e doloroso, mesmo que isso n\u00e3o seja imediatamente \u00f3bvio.<br \/>\n<strong>Anche se sembra insormontabile, dovete trovare la forza e il coraggio di smettere di guardare queste immagini.<\/strong><\/p>\n<h6>Dove trovare aiuto?<\/h6>\n<p>Vi sentite attratti dai bambini?<br \/>\nNon c&#8217;\u00e8 da vergognarsi nel chiedere aiuto, anzi, \u00e8 un segno di coraggio!<br \/>\nIn molti Paesi esistono istituzioni e associazioni che riuniscono specialisti formati per aiutare le persone che provano attrazione indesiderata per i bambini a gestire meglio le loro fantasie e a controllare meglio gli impulsi che possono avere.\u00a0<a href=\"https:\/\/vivotis.com\/it\/pedoaiuto\/#help\"><strong><u>Trova aiuto \u00bb<\/u><\/strong><\/a><br \/>\nSe nel vostro Paese non esiste un servizio specializzato, la possibilit\u00e0 di rivolgersi a un terapeuta dipende dal contesto culturale, professionale e legale locale. In alcuni Paesi, medici qualificati possono offrire un aiuto confidenziale a persone che stanno lottando con pensieri o sentimenti angoscianti. In altri Paesi questo potrebbe non essere possibile. Ciascuno deve valutare cosa sia appropriato e sicuro nel proprio ambiente.<br \/>\nAlcuni terapeuti possono indirizzarvi verso colleghi pi\u00f9 adatti ad aiutarvi, mentre altri potrebbero chiudere i battenti senza aiutarvi, ma non perdete mai la speranza!<\/p>\n<h6>Cosa devo fare se penso che qualcuno che conosco stia lottando con questa attrazione?<\/h6>\n<p>Potete parlare con calma a quella persona senza giudicarla. Raccontate ci\u00f2 che avete visto e provato e incoraggiatela a cercare aiuto presso uno specialista competente.<br \/>\nSi pu\u00f2 anche citare il progetto PedoHelp\u2122, che offre orientamento e informazioni.<\/p>\n<hr \/>\n<h4>Sugli abusi sessuali sui minori<\/h4>\n<h6>Che cos&#8217;\u00e8 l&#8217;abuso sessuale?<\/h6>\n<p>La violenza si verifica quando una persona impone intenzioni o comportamenti sessuali a un&#8217;altra persona, o perch\u00e9 questa non ha dato il proprio consenso, o perch\u00e9 non \u00e8 in grado di comprenderlo (ad esempio, un bambino o un giovane adolescente).<br \/>\nI bambini non sono in grado di dare il loro consenso al sesso perch\u00e9 non sanno ancora cosa sia e non devono saperlo. Sono troppo giovani e non sono pronti per capire o affrontare la sessualit\u00e0.<br \/>\nMettere un bambino in qualsiasi situazione che dia un significato o un contesto sessuale, anche quando ci\u00f2 avviene nell&#8217;ambito di un gioco, significa trasformarlo in un oggetto di soddisfazione per il proprio desiderio adulto o adolescenziale, e questo \u00e8 inaccettabile.<\/p>\n<h6>Chi sono i colpevoli?<\/h6>\n<p>Gli autori possono essere uomini o donne, adolescenti o adulti, e possono essere attratti o meno dai bambini. Alcuni autori sono pedofili (attratti dai bambini), ma la maggior parte non lo sono.<br \/>\nSpesso immaginiamo che gli abusatori siano sadici, perversi, manipolatori e calcolatori. Sebbene queste persone esistano, in realt\u00e0 sono molto rare. La stragrande maggioranza degli abusatori sessuali di minori sono persone dolci e premurose che amano veramente i bambini. Inoltre, spesso appaiono affidabili sia ai bambini che ai genitori.<br \/>\nLa maggior parte degli autori di tali attrazioni non ha mai cercato aiuto o parlato dei propri pensieri prima di agire.<\/p>\n<h6>Chi sono le vittime?<\/h6>\n<p>Qualsiasi bambino pu\u00f2 diventare vittima di abusi sessuali.<br \/>\nTuttavia, i bambini con buone competenze psicosociali, quelli che capiscono cosa \u00e8 e cosa non \u00e8 permesso e che conoscono le regole di base dei confini personali, sono maggiormente in grado di identificare i bambini, gli adolescenti e gli adulti che li fanno sentire a disagio e di osare dire loro di no. Questi bambini, quando si trovano di fronte a una situazione problematica, sono anche pi\u00f9 propensi a chiedere rapidamente aiuto a un adulto.<br \/>\nI bambini soli, abbandonati a se stessi, e quelli che non hanno una guida nelle relazioni con gli altri (competenze psicosociali deboli) o che non hanno compreso le regole dell&#8217;intimit\u00e0 (famiglie con confini sfumati o inadeguati) sono pi\u00f9 spesso vittime di violenza sessuale rispetto agli altri.<\/p>\n<h6>Quali sono le conseguenze dell&#8217;abuso sessuale su un bambino?<\/h6>\n<p>La violenza sessuale ha spesso conseguenze gravi, indipendentemente dall&#8217;et\u00e0 della vittima. Gli effetti variano a seconda del bambino, della natura dell&#8217;abuso, della sua frequenza, della relazione con l&#8217;abusante e del supporto terapeutico e legale successivo all&#8217;aggressione.<br \/>\nI postumi si manifestano spesso, in vario modo, in momenti diversi della vita.<br \/>\nAl di l\u00e0 delle possibili conseguenze fisiche o mediche, un bambino pu\u00f2 soffrire di molteplici conseguenze psicologiche come senso di colpa e vergogna, paura, ansia, rabbia, perdita di fiducia in se stesso, depressione, attacchi d&#8217;ansia, dolore cronico, isolamento sociale, sfiducia nei confronti di tutti gli adolescenti e\/o adulti, difficolt\u00e0 a formare relazioni intime sane, alterazione della memoria o della concentrazione, disturbi del sonno o disturbi alimentari&#8230;<br \/>\nLe aggressioni possono anche portare a comportamenti distruttivi: tentativi di suicidio, automutilazione, anoressia\/bulimia, prostituzione, delinquenza, comportamenti a rischio e dipendenze (da alcol, droghe o altre sostanze)&#8230;<br \/>\nL&#8217;abuso sessuale pu\u00f2 aumentare il rischio di difficolt\u00e0 successive, compresi i comportamenti inappropriati, anche se non \u00e8 inevitabile.<br \/>\nIl silenzio non \u00e8 inevitabile, cos\u00ec come non \u00e8 inevitabile la sofferenza. \u00c8 possibile recuperare e ricostruire la propria vita con l&#8217;aiuto di uno specialista qualificato.<\/p>\n<hr \/>\n<h4>Sul turismo sessuale minorile<\/h4>\n<h6>Quali bambini sono vittime del turismo sessuale?<\/h6>\n<p>Le vittime della prostituzione minorile sono sia ragazze che ragazzi. Spesso provengono da contesti sociali svantaggiati. Il turismo sessuale che coinvolge i bambini \u00e8 un fenomeno in crescita.<br \/>\nSe siete testimoni di un caso di turismo sessuale che coinvolge un minore nel vostro Paese o all&#8217;estero, segnalatelo immediatamente.<\/p>\n<h6>Quali sono i rischi?<\/h6>\n<p>I turisti sessuali provengono da tutti i contesti. Possono essere sposati o single, uomini o donne, ricchi o poveri, giovani o anziani. I turisti sessuali che abusano di bambini possono essere perseguiti nel loro Paese d&#8217;origine, se non sono stati perseguiti nel Paese in cui \u00e8 stato commesso il reato. I rischi sono enormi: una pena detentiva di diversi anni e multe molto salate, anche molti anni dopo l&#8217;abuso. Le condanne possono derivare dalla prostituzione minorile e anche da aggressioni sessuali, stupri, immagini sessuali di bambini e altri reati o tentativi di reati contro l&#8217;integrit\u00e0 dei bambini.<\/p>\n<h6>Il turismo sessuale contribuisce allo sviluppo economico di un paese?<\/h6>\n<p>I turisti che visitano un Paese per usare le persone per il loro piacere sessuale non fanno altro che incoraggiare la corruzione in questo Paese, lo sfruttamento e lo svilimento della sua popolazione.<\/p>\n<h6>\u00c8 una tradizione fare sesso con i bambini in Asia?<\/h6>\n<p>In alcuni Paesi, l&#8217;estrema povert\u00e0 spinge i genitori a spingere i figli a prostituirsi. Le reti di trafficanti usano i bambini in situazioni di vulnerabilit\u00e0 per arricchirsi, e altre persone approfittano di questa miseria per trasformarli in schiavi del sesso.<br \/>\nIn alcune regioni, miti dannosi sostengono che il contatto con un minore possa curare le malattie. In realt\u00e0, \u00e8 vero il contrario: i rapporti sessuali con i minori comportano infatti un elevato rischio di trasmissione di infezioni, tra cui l&#8217;HIV. Molto spesso, i minori che vengono sfruttati in queste situazioni non sono a conoscenza dei mezzi di prevenzione e protezione dalle malattie sessualmente trasmissibili.<br \/>\nIndipendentemente dal paese, dalla cultura, dalla tradizione o dalle convinzioni, un bambino non cerca mai di avere un&#8217;attivit\u00e0 sessuale o di essere consenziente.<\/p>\n<hr \/>\n<h4>Sui bambini<\/h4>\n<h6>Che cos&#8217;\u00e8 un ambiente familiare incestuoso?<\/h6>\n<p>Un ambiente familiare incestuoso \u00e8 quello in cui i normali confini tra le generazioni sono offuscati o infranti. I ruoli, gli spazi e la privacy non vengono rispettati e le relazioni si confondono in modi che violano i bisogni emotivi e di sviluppo del bambino.<br \/>\nIn alcune situazioni, questo ambiente pu\u00f2 includere comportamenti illegali o dannosi tra i membri della famiglia. In tutti i casi, quando \u00e8 coinvolto un bambino, questo \u00e8 dannoso e crea una grave confusione sull&#8217;identit\u00e0, l&#8217;autonomia e i confini personali. I bambini cresciuti in questi ambienti possono faticare a comprendere i limiti che proteggono se stessi e gli altri, e in seguito possono riprodurre comportamenti inappropriati senza rendersi conto che gli altri non condividono le stesse aspettative o esperienze.<\/p>\n<h6>Un bambino pu\u00f2 provare desiderio e piacere sessuale?<\/h6>\n<p>La sessualit\u00e0 emergente dei bambini \u00e8 molto diversa da quella degli adulti ed \u00e8 essenziale che queste due realt\u00e0 non vengano mai confuse.<br data-start=\"634\" data-end=\"637\" \/>Crescendo, i bambini esplorano il proprio corpo e sviluppano curiosit\u00e0 verso se stessi. In questa esplorazione possono trovare conforto o rassicurazione. Un bambino non dovrebbe mai essere incoraggiato, pressato, indirizzato o monitorato durante questi comportamenti privati, anche se con tenerezza e dolcezza.<\/p>\n<h6>Un bambino pu\u00f2 manifestare interesse per un comportamento sessuale?<\/h6>\n<p>I bambini non possiedono ancora la capacit\u00e0 psicologica o fisiologica di vivere consapevolmente e coscientemente un&#8217;esperienza sessuale. Possono dire a una persona pi\u00f9 grande che si sentono curiosi o interessati, oppure non osano dire di no perch\u00e9 vogliono renderla felice, ma questo non significa che capiscano o desiderino veramente queste esperienze.<br \/>\nQuando un adolescente o un adulto propone un atto sessuale a un bambino, quest&#8217;ultimo non sa di cosa si tratti, n\u00e9 se sia buono o cattivo per lui. \u00c8 troppo giovane per saperlo e non pu\u00f2 dire s\u00ec o no a qualcosa di cui non sa nulla. Possono essere curiosi, ma questo non significa mai che siano consenzienti. Ogni cosa ha il suo tempo: un bambino scoprir\u00e0 il sesso con qualcuno della sua et\u00e0 quando sar\u00e0 pi\u00f9 grande.<\/p>\n<h6>Come devo reagire quando un bambino si comporta in modo inappropriato nei confronti di una persona pi\u00f9 grande?<\/h6>\n<p>Un bambino pu\u00f2 essere turbato da qualcosa che ha vissuto, visto o sentito e pu\u00f2 avvicinarsi a un adolescente o a un adulto per fargli domande o agire in modi che superano i confini personali. Questo non \u00e8 mai espressione di un&#8217;intenzione o di un consenso genuino, ma \u00e8 semplicemente l&#8217;espressione di un bisogno di sapere o di verificare ci\u00f2 che \u00e8 permesso e ci\u00f2 che non \u00e8 permesso. L&#8217;adolescente o l&#8217;adulto deve sempre stabilire dei limiti, deve sempre ricordare ci\u00f2 che \u00e8 proibito e deve proteggere i bambini da ci\u00f2 che li ferisce.<\/p>\n<h6>La sessualit\u00e0 di un adulto pu\u00f2 influenzare o iniziare un bambino?<\/h6>\n<p>La scoperta del proprio e dell&#8217;altrui corpo \u00e8 un gioco piacevole solo se condiviso tra bambini della stessa et\u00e0 e con lo stesso livello di maturit\u00e0, che accettano di partecipare al gioco. Gli adulti devono intervenire se un bambino impone questo tipo di gioco a un altro bambino, o in caso di comportamenti sessuali problematici.<br \/>\nSebbene sia importante cercare di rispondere alle curiosit\u00e0 e alle domande dei bambini sulla sessualit\u00e0 con l&#8217;aiuto, se necessario, di libri adatti all&#8217;et\u00e0, ci\u00f2 dovrebbe sempre essere limitato alle loro domande e alla loro capacit\u00e0 di comprensione. \u00c8 sempre inopportuno e dannoso coinvolgere un bambino in qualsiasi comportamento che abbia un significato sessuale, sia attraverso il contatto fisico, le richieste o l&#8217;esposizione a materiale esplicito. Nessun atto sessuale con un bambino pu\u00f2 essere considerato istruttivo.<\/p>\n<h6>Cosa fare quando un bambino vede un&#8217;immagine pornografica?<\/h6>\n<p>A seconda dell&#8217;et\u00e0 e del livello di comprensione, si pu\u00f2 spiegare che la pornografia \u00e8 molto diversa dalle relazioni reali o dall&#8217;intimit\u00e0. Proprio come nei film, dove gli attori fingono di fare del male agli altri o di mostrare emozioni forti, gli attori professionisti fingono di provare piacere nelle immagini pornografiche. I loro movimenti sono bruschi e le loro pose sono studiate solo per l&#8217;impatto visivo, non per l&#8217;autenticit\u00e0. Gli attori e le attrici spesso consumano droghe per essere pi\u00f9 efficaci e spesso si sottopongono a interventi di chirurgia plastica per modificare il proprio corpo. A volte i peli del corpo vengono rasati e il trucco e l&#8217;illuminazione vengono utilizzati per cancellare brufoli, cicatrici o il colore naturale della pelle. La pornografia mostra il sesso, non una relazione sessuale d&#8217;amore.<\/p>\n<h6>L&#8217;inizio delle mestruazioni significa che una ragazza \u00e8 pronta per i rapporti intimi?<\/h6>\n<p>Le ragazze, come i ragazzi, hanno bisogno di tempo dopo l&#8217;inizio della pubert\u00e0 prima di essere pronte ad avere rapporti sessuali, perch\u00e9 la sessualit\u00e0 \u00e8 sia fisica che psicologica.<br \/>\nCostringere gli adolescenti al matrimonio o a relazioni intime solo perch\u00e9 sono biologicamente capaci di riprodursi \u00e8 abusivo e dannoso per il loro sviluppo e la loro vita futura.<\/p>\n<h6>Come sensibilizzare i bambini al rischio di abuso sessuale?<\/h6>\n<p>L&#8217;educazione sessuale, se adattata all&#8217;et\u00e0 e al livello di sviluppo dei bambini, li aiuta a sviluppare buone competenze psicosociali.<br \/>\nI bambini devono essere in grado di nominare le diverse parti del corpo, comprese le aree private come il pene, la vulva e l&#8217;ano, usando parole che non hanno paura di pronunciare di fronte agli adulti. Questi termini sono anatomici e appropriati e non devono mai essere considerati sporchi o vergognosi.<br \/>\nI bambini devono imparare a identificare le aree private e personali per rispettarle sul proprio corpo e su quello degli altri.<br \/>\nI bambini devono sapere che possono confidarsi con gli adulti e che questi ultimi sono disponibili ad ascoltarli.<\/p>\n<h6>Dobbiamo parlare con i bambini quando qualcuno di loro \u00e8 stato abusato sessualmente?<\/h6>\n<p>\u00c8 compito degli adulti proteggere i bambini, ma se per qualsiasi motivo si trovano da soli con qualcuno che potrebbe aggredirli, devono essere avvertiti per proteggersi.<br \/>\nIn altri casi, dovete rispondere alle domande dei vostri figli tenendo conto di ci\u00f2 che vogliono sapere e della loro et\u00e0. Un oscuro segreto di famiglia \u00e8 dannoso per lo sviluppo di un bambino, ma lo \u00e8 anche una rivelazione prematura. Non esitate a chiedere l&#8217;aiuto di un terapeuta che vi guidi e vi accompagni.<\/p>\n<h6>Come si riconosce una vittima di abuso sessuale su minore?<\/h6>\n<p>Spesso i bambini non hanno le conoscenze, l&#8217;esperienza o le parole per esprimere ci\u00f2 che hanno vissuto o sofferto, perch\u00e9 la sessualit\u00e0 \u00e8 un mondo sconosciuto per loro. Quindi esprimono la loro sofferenza e infelicit\u00e0 usando il loro corpo.<br \/>\nQualsiasi cambiamento improvviso nel comportamento o nell&#8217;aspetto dovrebbe indurre gli adulti a interrogarsi sulla causa del cambiamento.<br \/>\nIn caso di dubbio, consultare un professionista che possa porre le domande al bambino senza influenzare le sue risposte.<br \/>\nSe si sospetta che un bambino abbia subito un abuso, \u00e8 necessario segnalarlo immediatamente.<\/p>\n<h6>Qual \u00e8 la cosa migliore da fare se un bambino \u00e8 stato abusato?<\/h6>\n<p>Prima di tutto, mantenete la calma.<br \/>\nCredete ai bambini, aiutateli a esprimersi con le loro parole, senza aggiungere nulla e senza lasciarvi sopraffare dalle vostre preoccupazioni, dalla vostra immaginazione e dalla vostra conoscenza della sessualit\u00e0. Non chiedete loro di ripetersi o di raccontarvi pi\u00f9 volte ci\u00f2 che hanno vissuto.<br \/>\nPortarli tempestivamente presso le autorit\u00e0 o i servizi competenti (ad esempio, la polizia o la protezione dei minori) per essere assistiti da professionisti qualificati che raccoglieranno la loro testimonianza.<br \/>\nConsentire a professionisti qualificati di condurre qualsiasi interrogatorio e indagine.<br \/>\nPreoccuparsi del benessere dei bambini e della loro protezione senza mai cercare di fare giustizia da soli.<br \/>\nSe avete dei dubbi o se le parole dei bambini non sono chiare, potete portarli a consultare un terapeuta infantile.<br \/>\nIn ogni caso, dite ai bambini che hanno fatto bene a parlarvi, lodateli per il loro coraggio e ringraziateli per essersi fidati di voi.<br \/>\n<a href=\"https:\/\/childhelplineinternational.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Potete chiamare la linea di assistenza all&#8217;infanzia del vostro paese per fare una denuncia.<\/a><\/p>\n<h6>Cosa succede se il vostro bambino o adolescente si \u00e8 comportato in modo sessualmente dannoso nei confronti di un altro bambino?<\/h6>\n<p>Se i vostri figli hanno abusato di un altro bambino, \u00e8 possibile che essi stessi abbiano vissuto, visto o sentito cose che hanno turbato il loro benessere emotivo o di sviluppo. Offrite loro la possibilit\u00e0 di parlare con un terapeuta infantile e accompagnateli se sono d&#8217;accordo.<br \/>\nSarebbe anche opportuno consultare &#8211; da soli, accompagnati dal partner o con la famiglia &#8211; un terapeuta per riflettere sul funzionamento della vostra famiglia e capire perch\u00e9 i vostri figli non hanno imparato ci\u00f2 che \u00e8 fondamentalmente vietato.<\/p>\n<hr \/>\n<h4>Terapeuti: Quando un paziente riferisce un&#8217;attrazione sessuale per i minori<\/h4>\n<h6>Che cos&#8217;\u00e8 la pedofilia?<\/h6>\n<p>La pedofilia \u00e8 una parafilia riconosciuta nelle classificazioni diagnostiche psichiatriche. La maggior parte degli individui con questa attrazione non si impegna in comportamenti illegali o dannosi.<br \/>\nCome operatore sanitario, dovete innanzitutto ascoltare il disagio del paziente. Probabilmente \u00e8 per questo che il paziente si \u00e8 rivolto a voi; inoltre, il paziente si fida delle vostre capacit\u00e0 e della vostra buona volont\u00e0.<br \/>\nLa pedofilia si riferisce a un&#8217;attrazione sessuale persistente verso i bambini in et\u00e0 prepuberale.<br \/>\nLa pedofilia \u00e8 una condizione clinica classificata nell&#8217;ICD e nel DSM, i due principali sistemi diagnostici internazionali.<br \/>\nNell&#8217;ICD, la pedofilia \u00e8 elencata tra i disturbi delle preferenze sessuali e definita come \u201cuna preferenza sessuale per i bambini, maschi o femmine o entrambi, di solito in et\u00e0 prepuberale o puberale precoce\u201d.\u201d<br \/>\nNel DSM il disturbo pedofilo \u00e8 classificato come disturbo parafilico. Si riferisce a un interesse sessuale ricorrente e persistente per bambini prepuberi, della durata di almeno sei mesi, che coinvolge un bambino generalmente di et\u00e0 pari o inferiore a 13 anni e che causa un disagio significativo, una compromissione o un rischio di comportamento dannoso.<br \/>\nL&#8217;attrazione pedofila non \u00e8 una condizione uniforme. Le descrizioni cliniche distinguono diversi modelli: pu\u00f2 essere esclusiva o non esclusiva, diretta verso ragazze, ragazzi o entrambi, e gli individui possono essere astinenti o presentare diversi livelli di rischio. Queste variazioni descrivono solo la presentazione clinica e non riducono la responsabilit\u00e0 legale per le azioni dannose.<br \/>\nInfine, i soggetti con questa attrazione possono rimanere astinenti o presentare diversi livelli di rischio comportamentale.<\/p>\n<h6>Come si diventa pedofili?<\/h6>\n<p>Esiste un&#8217;ampia letteratura sugli individui che commettono reati contro i minori, sulla loro storia e sulle condizioni di comorbilit\u00e0; tuttavia, ci sono pochi dati relativi allo sviluppo di questa attrazione in persone che non l&#8217;hanno mai agita. Abbiamo comunque osservato che non \u00e8 rilevante confondere sistematicamente i due disturbi.<br \/>\nInoltre, il costrutto di qualsiasi tipo di preferenza sessuale rimane \u201cenigmatico\u201d a causa della sua complessit\u00e0 e della combinazione di vari aspetti. Oltre a circostanze individuali incontestabili, non dobbiamo dimenticare i fattori sociali nella sessualizzazione dei bambini (ad esempio, le rappresentazioni ipersessualizzate dei media).<\/p>\n<h6>Il mio paziente \u00e8 \u2018pericoloso\u2019?<\/h6>\n<p><strong>Ci sono segnali di allarme prima che l&#8217;atto abbia luogo?<\/strong><br \/>\nDa una prospettiva psicopatologica, ogni pericolo \u00e8 prima di tutto una vulnerabilit\u00e0. Un paziente che si sottopone a terapia ha meno rischi di mettere in atto comportamenti dannosi. Come operatori sanitari, dobbiamo innanzitutto occuparci di questa vulnerabilit\u00e0. Quando il legame terapeutico \u00e8 forte, non \u00e8 un tab\u00f9 chiedere al paziente di mettere in atto comportamenti dannosi. Il paziente pu\u00f2 allora capire che siete qui per aiutarlo e che esiste un&#8217;alternativa a un atto irreversibile.<br \/>\nNota: contrariamente all&#8217;opinione comune, l&#8217;uso di materiale pedopornografico (CSAM) non \u00e8 necessariamente il primo passo verso la messa in atto di comportamenti dannosi nei confronti di un minore. Gli studi sull&#8217;influenza delle immagini violente in generale non portano a conclusioni certe e inequivocabili. In alcuni casi, il consumo di tali immagini pu\u00f2 aiutare a gestire impulsi angoscianti, mentre in altri casi facilita la cristallizzazione di fantasie sessuali. Inoltre, non tutti i consumatori di pedopornografia sono pedofili&#8230;<\/p>\n<h6><strong>Esiste una cura per la pedofilia? Qual \u00e8 il mio ruolo come professionista della salute?<\/strong><\/h6>\n<p>Il primo elemento chiave, indipendentemente dalla vostra conoscenza della materia, \u00e8 quello di essere il destinatario della storia del paziente e, se del caso, del suo dolore e della sua angoscia, assicurandovi che le vostre percezioni (a volte negative) non interferiscano con le vostre capacit\u00e0 di ascolto e la vostra buona volont\u00e0.<br \/>\nEsistono strategie terapeutiche specifiche ed \u00e8 importante informare il paziente su di esse: psicoterapia analitica o cognitivo-comportamentale, approcci sessuologici, terapia farmacologica, ecc. A seconda delle vostre risorse e dei vostri limiti, potete consigliare al paziente un terapeuta o un istituto specializzato, oppure prenderlo in carico voi stessi.<br \/>\nL&#8217;obiettivo terapeutico non deve essere una cura intesa come cambiamento dell&#8217;attrazione sessuale della persona, che suonerebbe come una risposta alla pressione sociale e si scontrerebbe con i nostri limiti clinici, ma piuttosto la cura del dolore del paziente e delle sue cause. Ricordate che nella maggior parte dei casi il vostro paziente avr\u00e0 la vostra stessa percezione sociale della pedofilia!<br \/>\nGli obiettivi dell&#8217;assistenza terapeutica sono diversi: gestione degli impulsi e delle emozioni; cura delle ansie e\/o della depressione e dell&#8217;indebolimento dell&#8217;autostima; trattamento dei comportamenti di dipendenza, siano essi legati alle sostanze o al comportamento; disturbi della personalit\u00e0 (impulsivit\u00e0, scarsa tolleranza alla frustrazione, inibizione, ecc.), follow-up dei disturbi derivanti da abusi o negligenze (PTSD, ecc.), trattamento delle difficolt\u00e0 sessuali o relazionali co-occorrenti. L&#8217;incontro con il paziente sar\u00e0 fondamentale per valutare le sue esigenze e offrire un&#8217;assistenza adeguata.<\/p>\n<h6>Esistono trattamenti farmacologici?<\/h6>\n<p>\u00c8 possibile associare incontri di follow-up o psicoterapia e farmaci con l&#8217;obiettivo di ridurre e controllare i pensieri o i comportamenti associati a impulsi sessuali dannosi o inappropriati. Prima deve essere effettuata una valutazione e il paziente deve acconsentire a questo trattamento.<br \/>\nA seconda del Paese, alcuni farmaci sono approvati per questa indicazione. Per tutta la durata del trattamento \u00e8 necessaria una valutazione terapeutica preliminare e l&#8217;osservazione.<br \/>\nAlcuni studi fanno riferimento alla prescrizione di antidepressivi serotoninergici per alleviare gli atteggiamenti compulsivi e ansiosi presenti in alcuni pedofili, ma la vendita di tali farmaci potrebbe non essere autorizzata per questi scopi.<br \/>\nAltri trattamenti psicotropi possono essere utilizzati per migliorare alcune possibili comorbidit\u00e0.<br \/>\nPer saperne di pi\u00f9 sull&#8217;uso dei trattamenti farmacologici, visitate il sito\u00a0<a href=\"http:\/\/www.inahta.org\/\" rel=\"noopener\">il sito web della vostra agenzia sanitaria nazionale<\/a>.<\/p>\n<h6>Quando devo informare l&#8217;autorit\u00e0 giudiziaria?<\/h6>\n<p>Le leggi variano da Paese a Paese.<br \/>\nGli operatori sanitari possono essere soggetti al segreto professionale, a seconda di vari criteri (professione, istituzione, missione&#8230;).<br \/>\nSe ritenete che vi sia un obbligo o un rischio legale che richiede la divulgazione, potete contattare la polizia e\/o il sistema giudiziario del vostro paese.<\/p>\n<p><small><em>La Federazione francese dei CRIAVS ha contribuito allo sviluppo di queste linee guida.<\/em><\/small><\/p>\n<hr \/>\n<h1>La Carta<\/h1>\n<p><strong>Copiate e firmate questa carta per impegnarvi a non abusare mai di nessun bambino:<\/strong><\/p>\n<p>Ho attrazioni sessuali che non ho scelto e di cui non sono responsabile.<br \/>\nRiconosco la mia responsabilit\u00e0 per le mie scelte, le mie parole e le mie azioni.<br \/>\nRiconosco che i bambini sono persone a tutti gli effetti, dipendenti dagli adulti e bisognosi di protezione, cura e considerazione.<br \/>\nRiconosco che la sessualit\u00e0 dei bambini non \u00e8 uguale a quella degli adulti.<br \/>\nSono consapevole che i bambini non hanno raggiunto la maturit\u00e0 fisica e mentale che consente loro di acconsentire a un&#8217;esperienza sessuale.<br \/>\nSono consapevole che l&#8217;abuso sessuale ha conseguenze traumatiche, dolorose e invalidanti sulla vita di un bambino, indipendentemente dall&#8217;et\u00e0.<br \/>\nPertanto, mi impegno oggi e per il resto della mia vita a non abusare mai di nessun bambino.<br \/>\nSe un giorno mi ritrovo con un bambino e provo desiderio per lui\/lei, prometto di allontanarmi da questo bambino o di fare tutto il possibile affinch\u00e9 non soffra in alcun modo a causa del mio desiderio.<br \/>\nPrometto di non baciare o accarezzare mai un bambino mentre provo desiderio per lui\/lei.<br \/>\nPrometto di non esporre mai deliberatamente un bambino a una situazione che potrebbe turbarlo o eccitarlo sessualmente.<br \/>\nMi impegno a fare tutto il possibile per non trovarmi mai in una situazione in cui, sotto l&#8217;influenza di una sostanza o di una condizione medica, i miei impulsi sessuali possano annullare questo impegno.<br \/>\nMi impegno a rispettare questo impegno ora e per sempre.<\/p>\n<hr \/>\n<p><img decoding=\"async\" src=\"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp\" width=\"130px\" \/><\/p>\n<p><strong>Diffondiamo la consapevolezza in tutto il mondo.<br \/>\n<a href=\"https:\/\/www.paypal.com\/donate\/?hosted_button_id=VGV4ELBJYW95E\" rel=\"noopener\">Sostenete la nostra azione con una donazione.<\/a><\/strong><\/p>\n<p>Il progetto PedoHelp\u2122 \u00e8 stato sviluppato da un comitato etico, in collaborazione con organizzazioni partner in diversi Paesi, tra cui FFCRIAVS, ARTAAS, AIUS, SFSC e SNSC in Francia, PREVENSI in Spagna, PROSTASIA negli Stati Uniti e IO-NO! in Svizzera. Il progetto \u00e8 stato riconosciuto come \u201cPratica promettente\u201d dal Comitato di Lanzarote del Consiglio d&#8217;Europa. I suoi risultati\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=VnoVNhdmRJw\" target=\"_blank\" rel=\"noopener\">sono stati presentati anche<\/a>\u00a0al Comitato d&#8217;informazione del Senato francese.<\/p>\n<p><small>PedoHelp\u2122 \u00e8 un marchio di fabbrica, tutti i diritti riservati.<\/small><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1767683935428 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div style=\"display:flex; justify-content:center; margin:40px 0;\">\n  <div style=\"width:1120px; max-width:100%;\">\n    <div style=\"position:relative; padding-bottom:56.25%; height:0;\">\n      <iframe \n        src=\"https:\/\/www.youtube-nocookie.com\/embed\/OSlbanIPoQQ?si=woKoKeiSUxVt_LGs\"\n        title=\"Leitor de v\u00eddeo do YouTube\"\n        style=\"position:absolute; top:0; left:0; width:100%; height:100%;\"\n        frameborder=\"0\"\n        allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\"\n        referrerpolicy=\"strict-origin-when-cross-origin\"\n        allowfullscreen>\n      <\/iframe>\n    <\/div>\n  <\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1767683924617\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"templatera_shortcode\"><style type=\"text\/css\" data-type=\"vc_shortcodes-custom-css\">.vc_custom_1765116274052{margin-top: 0px !important;margin-bottom: 60px !important;background-color: #E3E3E3 !important;}.vc_custom_1765115037096{padding-bottom: 60px !important;}.vc_custom_1765115498022{margin-bottom: 60px !important;}<\/style><div id=\"help\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1765116274052 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1765115037096\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Diret\u00f3rio Internacional de Servi\u00e7os de Ajuda e Preven\u00e7\u00e3o<\/h1>\n<h2 data-start=\"316\" data-end=\"345\"><strong data-start=\"319\" data-end=\"345\">Global \/ Internacional<\/strong><\/h2>\n<ul data-start=\"347\" data-end=\"668\">\n<li data-start=\"347\" data-end=\"497\">\n<p data-start=\"349\" data-end=\"497\"><strong data-start=\"349\" data-end=\"393\">Desejo problem\u00e1tico - Auto-gest\u00e3o em linha<\/strong><br data-start=\"393\" data-end=\"396\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"398\" data-end=\"429\">https:\/\/troubled-desire.com\/en\/<\/a><br data-start=\"429\" data-end=\"432\" \/>Programa em linha de auto-gest\u00e3o para pessoas com dificuldades.<\/p>\n<\/li>\n<li data-start=\"499\" data-end=\"668\">\n<p data-start=\"501\" data-end=\"668\"><strong data-start=\"501\" data-end=\"565\">Apoio a menores atra\u00eddos por crian\u00e7as mais novas (MAP Resources)<\/strong><br data-start=\"565\" data-end=\"568\" \/><a class=\"decorated-link\" href=\"https:\/\/www.mapresources.info\/support\/minors\" target=\"_new\" rel=\"noopener\" data-start=\"570\" data-end=\"614\">https:\/\/www.mapresources.info\/support\/minors<\/a><br data-start=\"614\" data-end=\"617\" \/>Recursos para crian\u00e7as e adolescentes afectados.<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"670\" data-end=\"673\" \/>\n<h2 data-start=\"675\" data-end=\"708\"><strong data-start=\"678\" data-end=\"708\">\u00c1frica, M\u00e9dio Oriente, \u00cdndia<\/strong><\/h2>\n<h3 data-start=\"710\" data-end=\"723\"><strong data-start=\"714\" data-end=\"723\">\u00cdndia<\/strong><\/h3>\n<ul data-start=\"724\" data-end=\"1067\">\n<li data-start=\"724\" data-end=\"803\">\n<p data-start=\"726\" data-end=\"803\">Desejo perturbado: Auto-gest\u00e3o online<br data-start=\"765\" data-end=\"768\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"770\" data-end=\"801\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<li data-start=\"804\" data-end=\"859\">\n<p data-start=\"806\" data-end=\"859\">N\u00e3o ofender a \u00cdndia<br data-start=\"824\" data-end=\"827\" \/><a class=\"decorated-link\" href=\"https:\/\/dontoffendindia.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"829\" data-end=\"857\">https:\/\/dontoffendindia.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"860\" data-end=\"939\">\n<p data-start=\"862\" data-end=\"939\">Programa de preven\u00e7\u00e3o prim\u00e1ria da viol\u00eancia sexual<br data-start=\"911\" data-end=\"914\" \/><a class=\"decorated-link\" href=\"http:\/\/www.pppsv.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"916\" data-end=\"937\">http:\/\/www.pppsv.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"940\" data-end=\"1003\">\n<p data-start=\"942\" data-end=\"1003\">Troubled Desire (Hindi)<br data-start=\"965\" data-end=\"968\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/hi\/\" target=\"_new\" rel=\"noopener\" data-start=\"970\" data-end=\"1001\">https:\/\/troubled-desire.com\/hi\/<\/a><\/p>\n<\/li>\n<li data-start=\"1004\" data-end=\"1067\">\n<p data-start=\"1006\" data-end=\"1067\">Desejo conturbado (Marathi)<br data-start=\"1031\" data-end=\"1034\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/mr\/\" target=\"_new\" rel=\"noopener\" data-start=\"1036\" data-end=\"1067\">https:\/\/troubled-desire.com\/mr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1069\" data-end=\"1072\" \/>\n<h2 data-start=\"1074\" data-end=\"1093\"><strong data-start=\"1077\" data-end=\"1093\">\u00c1sia-Pac\u00edfico<\/strong><\/h2>\n<h3 data-start=\"1095\" data-end=\"1112\"><strong data-start=\"1099\" data-end=\"1112\">Austr\u00e1lia<\/strong><\/h3>\n<ul data-start=\"1113\" data-end=\"1277\">\n<li data-start=\"1113\" data-end=\"1199\">\n<p data-start=\"1115\" data-end=\"1199\">Parem j\u00e1 com isso!<br data-start=\"1127\" data-end=\"1130\" \/><a class=\"decorated-link\" href=\"https:\/\/phoenixhouse.com.au\/sexual-violence-and-offering-support\/\" target=\"_new\" rel=\"noopener\" data-start=\"1132\" data-end=\"1197\">https:\/\/phoenixhouse.com.au\/sexual-violence-and-offering-support\/<\/a><\/p>\n<\/li>\n<li data-start=\"1200\" data-end=\"1277\">\n<p data-start=\"1202\" data-end=\"1277\">Desejo perturbado: Auto-gest\u00e3o online<br data-start=\"1241\" data-end=\"1244\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"1246\" data-end=\"1277\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1279\" data-end=\"1292\"><strong data-start=\"1283\" data-end=\"1292\">Jap\u00e3o<\/strong><\/h3>\n<ul data-start=\"1293\" data-end=\"1499\">\n<li data-start=\"1293\" data-end=\"1383\">\n<p data-start=\"1295\" data-end=\"1383\">Associa\u00e7\u00e3o para refletir sobre o tratamento dos delinquentes sexuais<br data-start=\"1355\" data-end=\"1358\" \/><a class=\"decorated-link\" href=\"http:\/\/www.somec.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"1360\" data-end=\"1381\">http:\/\/www.somec.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"1384\" data-end=\"1499\">\n<p data-start=\"1386\" data-end=\"1499\">Grupo de toxicodepend\u00eancia sexual da Cl\u00ednica Enomoto<br data-start=\"1423\" data-end=\"1426\" \/><a class=\"decorated-link\" href=\"https:\/\/www.enomoto-clinic.jp\/care-list\/sexual-addiction-group-meeting\/\" target=\"_new\" rel=\"noopener\" data-start=\"1428\" data-end=\"1499\">https:\/\/www.enomoto-clinic.jp\/care-list\/sexual-addiction-group-meeting\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1501\" data-end=\"1504\" \/>\n<h2 data-start=\"1506\" data-end=\"1528\"><strong data-start=\"1509\" data-end=\"1528\">Europa e R\u00fassia<\/strong><\/h2>\n<h3 data-start=\"1530\" data-end=\"1545\"><strong data-start=\"1534\" data-end=\"1545\">\u00c1ustria<\/strong><\/h3>\n<ul data-start=\"1546\" data-end=\"1647\">\n<li data-start=\"1546\" data-end=\"1592\">\n<p data-start=\"1548\" data-end=\"1592\">Tratamento de \u00fatero<br data-start=\"1562\" data-end=\"1565\" \/><a class=\"decorated-link\" href=\"https:\/\/www.maenner.at\/\" target=\"_new\" rel=\"noopener\" data-start=\"1567\" data-end=\"1590\">https:\/\/www.maenner.at\/<\/a><\/p>\n<\/li>\n<li data-start=\"1593\" data-end=\"1647\">\n<p data-start=\"1595\" data-end=\"1647\">Coragem Beratung<br data-start=\"1611\" data-end=\"1614\" \/><a class=\"decorated-link\" href=\"http:\/\/www.courage-beratung.at\/\" target=\"_new\" rel=\"noopener\" data-start=\"1616\" data-end=\"1647\">http:\/\/www.courage-beratung.at\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1649\" data-end=\"1664\"><strong data-start=\"1653\" data-end=\"1664\">B\u00e9lgica<\/strong><\/h3>\n<ul data-start=\"1665\" data-end=\"1855\">\n<li data-start=\"1665\" data-end=\"1723\">\n<p data-start=\"1667\" data-end=\"1723\">Parem j\u00e1 com isso! Bruxelas<br data-start=\"1689\" data-end=\"1692\" \/><a class=\"decorated-link\" href=\"https:\/\/stopitnow.brussels\/\" target=\"_new\" rel=\"noopener\" data-start=\"1694\" data-end=\"1721\">https:\/\/stopitnow.brussels\/<\/a><\/p>\n<\/li>\n<li data-start=\"1724\" data-end=\"1766\">\n<p data-start=\"1726\" data-end=\"1766\">Parem j\u00e1 com isso!<br data-start=\"1738\" data-end=\"1741\" \/><a class=\"decorated-link\" href=\"https:\/\/stopitnow.be\/\" target=\"_new\" rel=\"noopener\" data-start=\"1743\" data-end=\"1764\">https:\/\/stopitnow.be\/<\/a><\/p>\n<\/li>\n<li data-start=\"1767\" data-end=\"1796\">\n<p data-start=\"1769\" data-end=\"1796\">S\u00e9OS<br data-start=\"1773\" data-end=\"1776\" \/><a class=\"decorated-link\" href=\"https:\/\/seos.be\/\" target=\"_new\" rel=\"noopener\" data-start=\"1778\" data-end=\"1794\">https:\/\/seos.be\/<\/a><\/p>\n<\/li>\n<li data-start=\"1797\" data-end=\"1855\">\n<p data-start=\"1799\" data-end=\"1855\">Desejo perturbado (FR)<br data-start=\"1819\" data-end=\"1822\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"1824\" data-end=\"1855\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1857\" data-end=\"1872\"><strong data-start=\"1861\" data-end=\"1872\">Cro\u00e1cia<\/strong><\/h3>\n<ul data-start=\"1873\" data-end=\"1939\">\n<li data-start=\"1873\" data-end=\"1939\">\n<p data-start=\"1875\" data-end=\"1939\">Cl\u00ednicas de Psiquiatria do Vrap\u010de<br data-start=\"1905\" data-end=\"1908\" \/><a class=\"decorated-link\" href=\"http:\/\/bolnica-vrapce.hr\/web\/\" target=\"_new\" rel=\"noopener\" data-start=\"1910\" data-end=\"1939\">http:\/\/bolnica-vrapce.hr\/web\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1941\" data-end=\"1956\"><strong data-start=\"1945\" data-end=\"1956\">Dinamarca<\/strong><\/h3>\n<ul data-start=\"1957\" data-end=\"2022\">\n<li data-start=\"1957\" data-end=\"2022\">\n<p data-start=\"1959\" data-end=\"2022\">Bryd Cirklen<br data-start=\"1971\" data-end=\"1974\" \/><a class=\"decorated-link\" href=\"https:\/\/www.psykiatri-regionh.dk\/bryd-cirklen\/\" target=\"_new\" rel=\"noopener\" data-start=\"1976\" data-end=\"2022\">https:\/\/www.psykiatri-regionh.dk\/bryd-cirklen\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2024\" data-end=\"2039\"><strong data-start=\"2028\" data-end=\"2039\">Est\u00f3nia<\/strong><\/h3>\n<ul data-start=\"2040\" data-end=\"2097\">\n<li data-start=\"2040\" data-end=\"2097\">\n<p data-start=\"2042\" data-end=\"2097\">Seksuaalh\u00e4ire n\u00f5uandetelefon<br data-start=\"2070\" data-end=\"2073\" \/><a class=\"decorated-link\" href=\"http:\/\/abikeskused.ee\/\" target=\"_new\" rel=\"noopener\" data-start=\"2075\" data-end=\"2097\">http:\/\/abikeskused.ee\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2099\" data-end=\"2114\"><strong data-start=\"2103\" data-end=\"2114\">Finl\u00e2ndia<\/strong><\/h3>\n<ul data-start=\"2115\" data-end=\"2195\">\n<li data-start=\"2115\" data-end=\"2162\">\n<p data-start=\"2117\" data-end=\"2162\">Otan Vastuun<br data-start=\"2129\" data-end=\"2132\" \/><a class=\"decorated-link\" href=\"http:\/\/www.otanvastuun.fi\/\" target=\"_new\" rel=\"noopener\" data-start=\"2134\" data-end=\"2160\">http:\/\/www.otanvastuun.fi\/<\/a><\/p>\n<\/li>\n<li data-start=\"2163\" data-end=\"2195\">\n<p data-start=\"2165\" data-end=\"2195\">Sexpo<br data-start=\"2170\" data-end=\"2173\" \/><a class=\"decorated-link\" href=\"http:\/\/www.sexpo.fi\/\" target=\"_new\" rel=\"noopener\" data-start=\"2175\" data-end=\"2195\">http:\/\/www.sexpo.fi\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2197\" data-end=\"2211\"><strong data-start=\"2201\" data-end=\"2211\">Fran\u00e7a<\/strong><\/h3>\n<ul data-start=\"2212\" data-end=\"2476\">\n<li data-start=\"2212\" data-end=\"2337\">\n<p data-start=\"2214\" data-end=\"2337\">N\u00famero STOP (Servi\u00e7o Telef\u00f3nico de Orienta\u00e7\u00e3o e de Preven\u00e7\u00e3o)<br data-start=\"2279\" data-end=\"2282\" \/><a class=\"decorated-link\" href=\"https:\/\/www.ffcriavs.org\/nos-actions\/numero-unique\/\" target=\"_new\" rel=\"noopener\" data-start=\"2284\" data-end=\"2335\">https:\/\/www.ffcriavs.org\/nos-actions\/numero-unique\/<\/a><\/p>\n<\/li>\n<li data-start=\"2338\" data-end=\"2417\">\n<p data-start=\"2340\" data-end=\"2417\">Associa\u00e7\u00e3o L'Ange Bleu<br data-start=\"2363\" data-end=\"2366\" \/><a class=\"decorated-link\" href=\"http:\/\/ange-bleu.com\/fr\/le-reseau-de-lange-bleu\" target=\"_new\" rel=\"noopener\" data-start=\"2368\" data-end=\"2415\">http:\/\/ange-bleu.com\/fr\/le-reseau-de-lange-bleu<\/a><\/p>\n<\/li>\n<li data-start=\"2418\" data-end=\"2476\">\n<p data-start=\"2420\" data-end=\"2476\">Desejo perturbado (FR)<br data-start=\"2440\" data-end=\"2443\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"2445\" data-end=\"2476\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2478\" data-end=\"2493\"><strong data-start=\"2482\" data-end=\"2493\">Alemanha<\/strong><\/h3>\n<ul data-start=\"2494\" data-end=\"2818\">\n<li data-start=\"2494\" data-end=\"2621\">\n<p data-start=\"2496\" data-end=\"2621\">Kein T\u00e4ter Werden (N\u00e3o ofender)<br data-start=\"2528\" data-end=\"2531\" \/><a class=\"decorated-link\" href=\"https:\/\/www.kein-taeter-werden.de\/\" target=\"_new\" rel=\"noopener\" data-start=\"2533\" data-end=\"2567\">https:\/\/www.kein-taeter-werden.de\/<\/a><br data-start=\"2567\" data-end=\"2570\" \/>- N\u00e3o ofender<br data-start=\"2586\" data-end=\"2589\" \/><a class=\"decorated-link\" href=\"https:\/\/www.dont-offend.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"2591\" data-end=\"2619\">https:\/\/www.dont-offend.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"2622\" data-end=\"2682\">\n<p data-start=\"2624\" data-end=\"2682\">Desejo perturbado (DE)<br data-start=\"2644\" data-end=\"2647\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/de\/\" target=\"_new\" rel=\"noopener\" data-start=\"2649\" data-end=\"2680\">https:\/\/troubled-desire.com\/de\/<\/a><\/p>\n<\/li>\n<li data-start=\"2683\" data-end=\"2818\">\n<p data-start=\"2685\" data-end=\"2818\">Voc\u00ea est\u00e1 a falar com eles<br data-start=\"2705\" data-end=\"2708\" \/><a class=\"decorated-link\" href=\"https:\/\/www.du-traeumst-von-ihnen.de\/\" target=\"_new\" rel=\"noopener\" data-start=\"2710\" data-end=\"2747\">https:\/\/www.du-traeumst-von-ihnen.de\/<\/a><br data-start=\"2747\" data-end=\"2750\" \/>- Apenas a sonhar com eles<br data-start=\"2775\" data-end=\"2778\" \/><a class=\"decorated-link\" href=\"https:\/\/www.just-dreaming-of-them.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"2780\" data-end=\"2818\">https:\/\/www.just-dreaming-of-them.org\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2820\" data-end=\"2835\"><strong data-start=\"2824\" data-end=\"2835\">Hungria<\/strong><\/h3>\n<ul data-start=\"2836\" data-end=\"2935\">\n<li data-start=\"2836\" data-end=\"2935\">\n<p data-start=\"2838\" data-end=\"2935\">Budapesti Szoci\u00e1lis Forr\u00e1sk\u00f6zpont<br data-start=\"2871\" data-end=\"2874\" \/><a class=\"decorated-link\" href=\"http:\/\/adhat.hu\/szervezet\/budapesti-szocialis-forraskozpont\" target=\"_new\" rel=\"noopener\" data-start=\"2876\" data-end=\"2935\">http:\/\/adhat.hu\/szervezet\/budapesti-szocialis-forraskozpont<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2937\" data-end=\"2952\"><strong data-start=\"2941\" data-end=\"2952\">Irlanda<\/strong><\/h3>\n<ul data-start=\"2953\" data-end=\"3135\">\n<li data-start=\"2953\" data-end=\"3025\">\n<p data-start=\"2955\" data-end=\"3025\">Stop It Now! Linha de apoio no Reino Unido e na Irlanda<br data-start=\"2989\" data-end=\"2992\" \/><a class=\"decorated-link\" href=\"https:\/\/www.stopitnow.org.uk\/\" target=\"_new\" rel=\"noopener\" data-start=\"2994\" data-end=\"3023\">https:\/\/www.stopitnow.org.uk\/<\/a><\/p>\n<\/li>\n<li data-start=\"3026\" data-end=\"3081\">\n<p data-start=\"3028\" data-end=\"3081\">Um em cada quatro<br data-start=\"3039\" data-end=\"3042\" \/><a class=\"decorated-link\" href=\"https:\/\/www.oneinfour.ie\/prevention\" target=\"_new\" rel=\"noopener\" data-start=\"3044\" data-end=\"3079\">https:\/\/www.oneinfour.ie\/prevention<\/a><\/p>\n<\/li>\n<li data-start=\"3082\" data-end=\"3135\">\n<p data-start=\"3084\" data-end=\"3135\">Desejo conturbado<br data-start=\"3099\" data-end=\"3102\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"3104\" data-end=\"3135\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3137\" data-end=\"3150\"><strong data-start=\"3141\" data-end=\"3150\">It\u00e1lia<\/strong><\/h3>\n<ul data-start=\"3151\" data-end=\"3213\">\n<li data-start=\"3151\" data-end=\"3213\">\n<p data-start=\"3153\" data-end=\"3213\">Parem j\u00e1 com isso!<br data-start=\"3165\" data-end=\"3168\" \/><a class=\"decorated-link\" href=\"http:\/\/get-help.stopitnow.org.uk\/it\/home-it\" target=\"_new\" rel=\"noopener\" data-start=\"3170\" data-end=\"3213\">http:\/\/get-help.stopitnow.org.uk\/it\/home-it<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3215\" data-end=\"3229\"><strong data-start=\"3219\" data-end=\"3229\">Let\u00f3nia<\/strong><\/h3>\n<ul data-start=\"3230\" data-end=\"3292\">\n<li data-start=\"3230\" data-end=\"3292\">\n<p data-start=\"3232\" data-end=\"3292\">Psicossom\u00e1tica<br data-start=\"3255\" data-end=\"3258\" \/><a class=\"decorated-link\" href=\"http:\/\/psihosomatika.lv\/kontakti\" target=\"_new\" rel=\"noopener\" data-start=\"3260\" data-end=\"3292\">http:\/\/psihosomatika.lv\/kontakti<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3294\" data-end=\"3312\"><strong data-start=\"3298\" data-end=\"3312\">Luxemburgo<\/strong><\/h3>\n<ul data-start=\"3313\" data-end=\"3422\">\n<li data-start=\"3313\" data-end=\"3363\">\n<p data-start=\"3315\" data-end=\"3363\">Linha direta contra a viol\u00eancia<br data-start=\"3335\" data-end=\"3338\" \/><a class=\"decorated-link\" href=\"http:\/\/www.euline.eu\/\" target=\"_new\" rel=\"noopener\" data-start=\"3340\" data-end=\"3361\">http:\/\/www.euline.eu\/<\/a><\/p>\n<\/li>\n<li data-start=\"3364\" data-end=\"3422\">\n<p data-start=\"3366\" data-end=\"3422\">Desejo perturbado (FR)<br data-start=\"3386\" data-end=\"3389\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"3391\" data-end=\"3422\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3424\" data-end=\"3443\"><strong data-start=\"3428\" data-end=\"3443\">Pa\u00edses Baixos<\/strong><\/h3>\n<ul data-start=\"3444\" data-end=\"3488\">\n<li data-start=\"3444\" data-end=\"3488\">\n<p data-start=\"3446\" data-end=\"3488\">Parem j\u00e1 com isso!<br data-start=\"3458\" data-end=\"3461\" \/><a class=\"decorated-link\" href=\"https:\/\/www.stopitnow.nl\/\" target=\"_new\" rel=\"noopener\" data-start=\"3463\" data-end=\"3488\">https:\/\/www.stopitnow.nl\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3490\" data-end=\"3504\"><strong data-start=\"3494\" data-end=\"3504\">Noruega<\/strong><\/h3>\n<ul data-start=\"3505\" data-end=\"3554\">\n<li data-start=\"3505\" data-end=\"3554\">\n<p data-start=\"3507\" data-end=\"3554\">A ajuda final<br data-start=\"3523\" data-end=\"3526\" \/><a class=\"decorated-link\" href=\"https:\/\/detfinneshjelp.no\/\" target=\"_new\" rel=\"noopener\" data-start=\"3528\" data-end=\"3554\">https:\/\/detfinneshjelp.no\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3556\" data-end=\"3572\"><strong data-start=\"3560\" data-end=\"3572\">Portugal<\/strong><\/h3>\n<ul data-start=\"3573\" data-end=\"3626\">\n<li data-start=\"3573\" data-end=\"3626\">\n<p data-start=\"3575\" data-end=\"3626\">Desejo conturbado<br data-start=\"3590\" data-end=\"3593\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"3595\" data-end=\"3626\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3628\" data-end=\"3644\"><strong data-start=\"3632\" data-end=\"3644\">Eslov\u00e9nia<\/strong><\/h3>\n<ul data-start=\"3645\" data-end=\"3790\">\n<li data-start=\"3645\" data-end=\"3790\">\n<p data-start=\"3647\" data-end=\"3790\">Javni zavodi - zdravstveni domovi<br data-start=\"3680\" data-end=\"3683\" \/><a class=\"decorated-link\" href=\"http:\/\/www.mz.gov.si\/si\/pogoste_vsebine_za_javnost\/strokovne_institucije\/javni_zavodi_zdravstveni_domovi\/\" target=\"_new\" rel=\"noopener\" data-start=\"3685\" data-end=\"3790\">http:\/\/www.mz.gov.si\/si\/pogoste_vsebine_za_javnost\/strokovne_institucije\/javni_zavodi_zdravstveni_domovi\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3792\" data-end=\"3805\"><strong data-start=\"3796\" data-end=\"3805\">Espanha<\/strong><\/h3>\n<ul data-start=\"3806\" data-end=\"3944\">\n<li data-start=\"3806\" data-end=\"3843\">\n<p data-start=\"3808\" data-end=\"3843\">PrevenSi<br data-start=\"3816\" data-end=\"3819\" \/><a class=\"decorated-link\" href=\"https:\/\/prevensi.es\/\" target=\"_new\" rel=\"noopener\" data-start=\"3821\" data-end=\"3841\">https:\/\/prevensi.es\/<\/a><\/p>\n<\/li>\n<li data-start=\"3844\" data-end=\"3885\">\n<p data-start=\"3846\" data-end=\"3885\">Anjo Blau<br data-start=\"3856\" data-end=\"3859\" \/><a class=\"decorated-link\" href=\"https:\/\/angelblau.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"3861\" data-end=\"3883\">https:\/\/angelblau.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"3886\" data-end=\"3944\">\n<p data-start=\"3888\" data-end=\"3944\">Desejo perturbado (ES)<br data-start=\"3908\" data-end=\"3911\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/es\/\" target=\"_new\" rel=\"noopener\" data-start=\"3913\" data-end=\"3944\">https:\/\/troubled-desire.com\/es\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3946\" data-end=\"3960\"><strong data-start=\"3950\" data-end=\"3960\">Su\u00e9cia<\/strong><\/h3>\n<ul data-start=\"3961\" data-end=\"3999\">\n<li data-start=\"3961\" data-end=\"3999\">\n<p data-start=\"3963\" data-end=\"3999\">Preventell<br data-start=\"3973\" data-end=\"3976\" \/><a class=\"decorated-link\" href=\"http:\/\/preventell.se\/\" target=\"_new\" rel=\"noopener\" data-start=\"3978\" data-end=\"3999\">http:\/\/preventell.se\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"4001\" data-end=\"4020\"><strong data-start=\"4005\" data-end=\"4020\">Su\u00ed\u00e7a<\/strong><\/h3>\n<ul data-start=\"4021\" data-end=\"4301\">\n<li data-start=\"4021\" data-end=\"4073\">\n<p data-start=\"4023\" data-end=\"4073\">Associa\u00e7\u00e3o DIS NO (FR)<br data-start=\"4046\" data-end=\"4049\" \/><a class=\"decorated-link\" href=\"http:\/\/www.disno.ch\/\" target=\"_new\" rel=\"noopener\" data-start=\"4051\" data-end=\"4071\">http:\/\/www.disno.ch\/<\/a><\/p>\n<\/li>\n<li data-start=\"4074\" data-end=\"4134\">\n<p data-start=\"4076\" data-end=\"4134\">Desejo perturbado (FR)<br data-start=\"4096\" data-end=\"4099\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"4101\" data-end=\"4132\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<li data-start=\"4135\" data-end=\"4181\">\n<p data-start=\"4137\" data-end=\"4181\">Beforemore (DE)<br data-start=\"4152\" data-end=\"4155\" \/><a class=\"decorated-link\" href=\"https:\/\/beforemore.ch\/\" target=\"_new\" rel=\"noopener\" data-start=\"4157\" data-end=\"4179\">https:\/\/beforemore.ch\/<\/a><\/p>\n<\/li>\n<li data-start=\"4182\" data-end=\"4242\">\n<p data-start=\"4184\" data-end=\"4242\">Desejo perturbado (DE)<br data-start=\"4204\" data-end=\"4207\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/de\/\" target=\"_new\" rel=\"noopener\" data-start=\"4209\" data-end=\"4240\">https:\/\/troubled-desire.com\/de\/<\/a><\/p>\n<\/li>\n<li data-start=\"4243\" data-end=\"4301\">\n<p data-start=\"4245\" data-end=\"4301\">Desejo perturbado (IT)<br data-start=\"4265\" data-end=\"4268\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/it\/\" target=\"_new\" rel=\"noopener\" data-start=\"4270\" data-end=\"4301\">https:\/\/troubled-desire.com\/it\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"4303\" data-end=\"4325\"><strong data-start=\"4307\" data-end=\"4325\">Reino Unido<\/strong><\/h3>\n<ul data-start=\"4326\" data-end=\"4489\">\n<li data-start=\"4326\" data-end=\"4398\">\n<p data-start=\"4328\" data-end=\"4398\">Stop it Now! Linha de apoio no Reino Unido e na Irlanda<br data-start=\"4362\" data-end=\"4365\" \/><a class=\"decorated-link\" href=\"https:\/\/www.stopitnow.org.uk\/\" target=\"_new\" rel=\"noopener\" data-start=\"4367\" data-end=\"4396\">https:\/\/www.stopitnow.org.uk\/<\/a><\/p>\n<\/li>\n<li data-start=\"4399\" data-end=\"4435\">\n<p data-start=\"4401\" data-end=\"4435\">StopSO<br data-start=\"4407\" data-end=\"4410\" \/><a class=\"decorated-link\" href=\"http:\/\/stopso.org.uk\/\" target=\"_new\" rel=\"noopener\" data-start=\"4412\" data-end=\"4433\">http:\/\/stopso.org.uk\/<\/a><\/p>\n<\/li>\n<li data-start=\"4436\" data-end=\"4489\">\n<p data-start=\"4438\" data-end=\"4489\">Desejo conturbado<br data-start=\"4453\" data-end=\"4456\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"4458\" data-end=\"4489\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"4491\" data-end=\"4494\" \/>\n<h2 data-start=\"4496\" data-end=\"4528\"><strong data-start=\"4499\" data-end=\"4528\">Am\u00e9rica Latina e Cara\u00edbas<\/strong><\/h2>\n<h3 data-start=\"4530\" data-end=\"4564\"><strong data-start=\"4534\" data-end=\"4564\">Pa\u00edses de l\u00edngua espanhola<\/strong><\/h3>\n<ul data-start=\"4565\" data-end=\"4665\">\n<li data-start=\"4565\" data-end=\"4606\">\n<p data-start=\"4567\" data-end=\"4606\">Anjo Blau<br data-start=\"4577\" data-end=\"4580\" \/><a class=\"decorated-link\" href=\"https:\/\/angelblau.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"4582\" data-end=\"4604\">https:\/\/angelblau.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"4607\" data-end=\"4665\">\n<p data-start=\"4609\" data-end=\"4665\">Desejo perturbado (ES)<br data-start=\"4629\" data-end=\"4632\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/es\/\" target=\"_new\" rel=\"noopener\" data-start=\"4634\" data-end=\"4665\">https:\/\/troubled-desire.com\/es\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"4667\" data-end=\"4704\"><strong data-start=\"4671\" data-end=\"4704\">Pa\u00edses de l\u00edngua portuguesa<\/strong><\/h3>\n<ul data-start=\"4705\" data-end=\"4763\">\n<li data-start=\"4705\" data-end=\"4763\">\n<p data-start=\"4707\" data-end=\"4763\">Desejo perturbado<br data-start=\"4727\" data-end=\"4730\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/pt\/\" target=\"_new\" rel=\"noopener\" data-start=\"4732\" data-end=\"4763\">https:\/\/troubled-desire.com\/pt\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"4765\" data-end=\"4768\" \/>\n<h2 data-start=\"4770\" data-end=\"4790\"><strong data-start=\"4773\" data-end=\"4790\">Am\u00e9rica do Norte<\/strong><\/h2>\n<h3 data-start=\"4792\" data-end=\"4806\"><strong data-start=\"4796\" data-end=\"4806\">Canad\u00e1<\/strong><\/h3>\n<ul data-start=\"4807\" data-end=\"5023\">\n<li data-start=\"4807\" data-end=\"4862\">\n<p data-start=\"4809\" data-end=\"4862\">Falar para mudar<br data-start=\"4827\" data-end=\"4830\" \/><a class=\"decorated-link\" href=\"https:\/\/talkingforchange.ca\/\" target=\"_new\" rel=\"noopener\" data-start=\"4832\" data-end=\"4860\">https:\/\/talkingforchange.ca\/<\/a><\/p>\n<\/li>\n<li data-start=\"4863\" data-end=\"4923\">\n<p data-start=\"4865\" data-end=\"4923\">Desejo perturbado (EN)<br data-start=\"4885\" data-end=\"4888\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"4890\" data-end=\"4921\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<li data-start=\"4924\" data-end=\"4964\">\n<p data-start=\"4926\" data-end=\"4964\">\u00c7a suffit<br data-start=\"4935\" data-end=\"4938\" \/><a class=\"decorated-link\" href=\"https:\/\/casuffit.info\/\" target=\"_new\" rel=\"noopener\" data-start=\"4940\" data-end=\"4962\">https:\/\/casuffit.info\/<\/a><\/p>\n<\/li>\n<li data-start=\"4965\" data-end=\"5023\">\n<p data-start=\"4967\" data-end=\"5023\">Desejo perturbado (FR)<br data-start=\"4987\" data-end=\"4990\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"4992\" data-end=\"5023\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"5025\" data-end=\"5036\"><strong data-start=\"5029\" data-end=\"5036\">EUA<\/strong><\/h3>\n<ul data-start=\"5037\" data-end=\"5461\">\n<li data-start=\"5037\" data-end=\"5094\">\n<p data-start=\"5039\" data-end=\"5094\">ASAP Internacional<br data-start=\"5057\" data-end=\"5060\" \/><a class=\"decorated-link\" href=\"https:\/\/asapinternational.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5062\" data-end=\"5092\">https:\/\/asapinternational.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5095\" data-end=\"5128\">\n<p data-start=\"5097\" data-end=\"5128\">ATSA<br data-start=\"5101\" data-end=\"5104\" \/><a class=\"decorated-link\" href=\"http:\/\/www.atsa.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"5106\" data-end=\"5126\">http:\/\/www.atsa.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"5129\" data-end=\"5167\">\n<p data-start=\"5131\" data-end=\"5167\">B4U-ACT<br data-start=\"5138\" data-end=\"5141\" \/><a class=\"decorated-link\" href=\"http:\/\/www.b4uact.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5143\" data-end=\"5165\">http:\/\/www.b4uact.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5168\" data-end=\"5228\">\n<p data-start=\"5170\" data-end=\"5228\">Prostasia - Obter ajuda<br data-start=\"5190\" data-end=\"5193\" \/><a class=\"decorated-link\" href=\"https:\/\/prostasia.org\/get-help\/\" target=\"_new\" rel=\"noopener\" data-start=\"5195\" data-end=\"5226\">https:\/\/prostasia.org\/get-help\/<\/a><\/p>\n<\/li>\n<li data-start=\"5229\" data-end=\"5294\">\n<p data-start=\"5231\" data-end=\"5294\">Recurso para criminosos sexuais<br data-start=\"5252\" data-end=\"5255\" \/><a class=\"decorated-link\" href=\"http:\/\/www.sexoffenderresource.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"5257\" data-end=\"5292\">http:\/\/www.sexoffenderresource.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"5295\" data-end=\"5341\">\n<p data-start=\"5297\" data-end=\"5341\">Parem j\u00e1 com isso!<br data-start=\"5309\" data-end=\"5312\" \/><a class=\"decorated-link\" href=\"http:\/\/www.stopitnow.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5314\" data-end=\"5339\">http:\/\/www.stopitnow.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5342\" data-end=\"5415\">\n<p data-start=\"5344\" data-end=\"5415\">Procura-se ajuda (curso em linha)<br data-start=\"5371\" data-end=\"5374\" \/><a class=\"decorated-link\" href=\"https:\/\/www.helpwantedprevention.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5376\" data-end=\"5413\">https:\/\/www.helpwantedprevention.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5416\" data-end=\"5461\">\n<p data-start=\"5418\" data-end=\"5461\">Ped\u00f3filos virtuosos<br data-start=\"5437\" data-end=\"5440\" \/><a class=\"decorated-link\" href=\"https:\/\/virped.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5442\" data-end=\"5461\">https:\/\/virped.org\/<\/a><\/p>\n<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1765115498022\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><small>N\u00e3o somos respons\u00e1veis pelo conte\u00fado oferecido nos s\u00edtios Web indicados nesta p\u00e1gina.<\/small><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\r\n<\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"\ud83c\udf10 Language \u25be \ud83c\uddec\ud83c\udde7 English \ud83c\uddeb\ud83c\uddf7 Fran\u00e7ais \ud83c\uddf3\ud83c\uddf1 Nederlands \ud83c\udde9\ud83c\uddea Deutsch \ud83c\uddea\ud83c\uddf8 Espa\u00f1ol \ud83c\uddee\ud83c\uddf9 Italiano \ud83c\uddf5\ud83c\uddf9 Portugu\u00eas \ud83c\uddf5\ud83c\uddf1 Polski \ud83c\uddf7\ud83c\uddfa \u0420\u0443\u0441\u0441\u043a\u0438\u0439 \ud83c\uddf9\ud83c\uddf7 T\u00fcrk\u00e7e \ud83c\uddf8\ud83c\udde6 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \ud83c\uddee\ud83c\uddf3 \u0939\u093f\u0928\u094d\u0926\u0940 \ud83c\uddef\ud83c\uddf5 \u65e5\u672c\u8a9e \ud83c\uddf0\ud83c\uddf7 \ud55c\uad6d\uc5b4 \ud83c\udde8\ud83c\uddf3 \u4e2d\u6587 Offrire comprensione e sostegno per prevenire gli abusi sessuali sui minori Non si scelgono le proprie fantasie Si sente attratto dai bambini [...]","protected":false},"author":1,"featured_media":0,"parent":1850,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pmpro_default_level":"","footnotes":""},"class_list":["post-2499","page","type-page","status-publish","hentry","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PedoHelp IT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedo.help\/it\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PedoHelp IT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedo.help\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"Vivotis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T08:19:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pedo.help\\\/it\\\/\",\"url\":\"https:\\\/\\\/pedo.help\\\/it\\\/\",\"name\":\"PedoHelp IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vivotis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pedo.help\\\/it\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pedo.help\\\/it\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ph-ppdonation.webp\",\"datePublished\":\"2026-01-06T07:05:44+00:00\",\"dateModified\":\"2026-01-06T08:19:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pedo.help\\\/it\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pedo.help\\\/it\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/pedo.help\\\/it\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ph-ppdonation.webp\",\"contentUrl\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ph-ppdonation.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pedo.help\\\/it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vivotis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PedoHelp\",\"item\":\"https:\\\/\\\/pedo.help\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PedoHelp IT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vivotis.com\\\/#website\",\"url\":\"https:\\\/\\\/vivotis.com\\\/\",\"name\":\"Vivotis\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/vivotis.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vivotis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vivotis.com\\\/#organization\",\"name\":\"Vivotis\",\"url\":\"https:\\\/\\\/vivotis.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vivotis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-brand-000000-m-scaled.png\",\"contentUrl\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-brand-000000-m-scaled.png\",\"width\":2560,\"height\":1281,\"caption\":\"Vivotis\"},\"image\":{\"@id\":\"https:\\\/\\\/vivotis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PedoHelp IT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedo.help\/it\/","og_locale":"pt_PT","og_type":"article","og_title":"PedoHelp IT","og_url":"https:\/\/pedo.help\/it\/","og_site_name":"Vivotis","article_modified_time":"2026-01-06T08:19:14+00:00","og_image":[{"url":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"25 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pedo.help\/it\/","url":"https:\/\/pedo.help\/it\/","name":"PedoHelp IT","isPartOf":{"@id":"https:\/\/vivotis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pedo.help\/it\/#primaryimage"},"image":{"@id":"https:\/\/pedo.help\/it\/#primaryimage"},"thumbnailUrl":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp","datePublished":"2026-01-06T07:05:44+00:00","dateModified":"2026-01-06T08:19:14+00:00","breadcrumb":{"@id":"https:\/\/pedo.help\/it\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pedo.help\/it\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/pedo.help\/it\/#primaryimage","url":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp","contentUrl":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/pedo.help\/it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vivotis.com\/"},{"@type":"ListItem","position":2,"name":"PedoHelp","item":"https:\/\/pedo.help\/"},{"@type":"ListItem","position":3,"name":"PedoHelp IT"}]},{"@type":"WebSite","@id":"https:\/\/vivotis.com\/#website","url":"https:\/\/vivotis.com\/","name":"Vivotis","description":"","publisher":{"@id":"https:\/\/vivotis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vivotis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/vivotis.com\/#organization","name":"Vivotis","url":"https:\/\/vivotis.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vivotis.com\/#\/schema\/logo\/image\/","url":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/11\/logo-brand-000000-m-scaled.png","contentUrl":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/11\/logo-brand-000000-m-scaled.png","width":2560,"height":1281,"caption":"Vivotis"},"image":{"@id":"https:\/\/vivotis.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/pages\/2499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/comments?post=2499"}],"version-history":[{"count":0,"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/pages\/2499\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/pages\/1850"}],"wp:attachment":[{"href":"https:\/\/vivotis.com\/pt\/wp-json\/wp\/v2\/media?parent=2499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}