{"id":2506,"date":"2026-01-06T07:05:44","date_gmt":"2026-01-06T07:05:44","guid":{"rendered":"https:\/\/vivotis.com\/?page_id=2506"},"modified":"2026-01-06T08:18:04","modified_gmt":"2026-01-06T08:18:04","slug":"de","status":"publish","type":"page","link":"https:\/\/vivotis.com\/nl\/pedohelp\/de\/","title":{"rendered":"PedoHelp DE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"lang-dropdown\">\n  <button class=\"lang-current\">\n    <span class=\"flag\">\ud83c\udf10<\/span>\n    <span class=\"label\">Taal<\/span>\n    <span class=\"arrow\">\u25be<\/span>\n  <\/button>\n\n  <ul class=\"lang-list\">\n    <li><a href=\"https:\/\/pedo.help\/\"><span class=\"flag\">\ud83c\uddec\ud83c\udde7<\/span> Engels<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/fr\/\"><span class=\"flag\">\ud83c\uddeb\ud83c\uddf7<\/span> Fran\u00e7ais<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/nl\/\"><span class=\"flag\">\ud83c\uddf3\ud83c\uddf1<\/span> Nederlands<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/de\/\"><span class=\"flag\">\ud83c\udde9\ud83c\uddea<\/span> Deutsch<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/es\/\"><span class=\"flag\">\ud83c\uddea\ud83c\uddf8<\/span> Espa\u00f1ol<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/it\/\"><span class=\"flag\">\ud83c\uddee\ud83c\uddf9<\/span> Italiano<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/pt\/\"><span class=\"flag\">\ud83c\uddf5\ud83c\uddf9<\/span> Portugees<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/pl\/\"><span class=\"flag\">\ud83c\uddf5\ud83c\uddf1<\/span> Polski<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ru\/\"><span class=\"flag\">\ud83c\uddf7\ud83c\uddfa<\/span> \u0420\u0443\u0441\u0441\u043a\u0438\u0439<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/tr\/\"><span class=\"flag\">\ud83c\uddf9\ud83c\uddf7<\/span> T\u00fcrk\u00e7e<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ar\/\"><span class=\"flag\">\ud83c\uddf8\ud83c\udde6<\/span> \u0627\u0644\u0639\u0631\u0628\u064a\u0629<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/hi\/\"><span class=\"flag\">\ud83c\uddee\ud83c\uddf3<\/span> \u0939\u093f\u0928\u094d\u0926\u0940<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ja\/\"><span class=\"flag\">\ud83c\uddef\ud83c\uddf5<\/span> \u65e5\u672c\u8a9e<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/ko\/\"><span class=\"flag\">\ud83c\uddf0\ud83c\uddf7<\/span> BEWEEG ROND<\/a><\/li>\n    <li><a href=\"https:\/\/pedo.help\/zh\/\"><span class=\"flag\">\ud83c\udde8\ud83c\uddf3<\/span> \u4e2d\u6587<\/a><\/li>\n  <\/ul>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h4>Verst\u00e4ndnis und Unterst\u00fctzung bei der Pr\u00e4vention von sexuellem Kindesmissbrauch<\/h4>\n<h5>Man sucht sich seine Fantasien nicht aus<\/h5>\n<p><strong>F\u00fchlen Sie sich zu Kindern hingezogen und haben Sie Angst, dass Sie sp\u00e4ter ein Kind missbrauchen k\u00f6nnten?<\/strong>\u00a0Machen Ihre Fantasien Sie ungl\u00fccklich? M\u00f6chten Sie manchmal masturbieren, w\u00e4hrend Sie sich Bilder von Kindern ansehen? Bevor Sie eine unwiderrufliche Tat begehen oder sich mit Schamgef\u00fchlen einsperren,\u00a0<strong>nehmen Sie sich die Zeit, diese Seite zu lesen.<\/strong><\/p>\n<h5>Keine Scham, kein Tabu<\/h5>\n<p>Sie sind nicht verantwortlich f\u00fcr Ihre Fantasien, aber Sie sind verantwortlich f\u00fcr alle Ihre Entscheidungen und f\u00fcr alle Ihre Handlungen.<br \/>\nIn vielen L\u00e4ndern gibt es Fachleute und Verb\u00e4nde, die helfen k\u00f6nnen.\u00a0<a href=\"https:\/\/vivotis.com\/de\/pedohelp\/#help\"><strong><u>Hilfe finden \u00bb<\/u><\/strong><\/a><\/p>\n<hr \/>\n<h5>Ich m\u00f6chte Sex mit einem Kind haben<\/h5>\n<p>Lassen Sie sich nicht von Ihren eigenen W\u00fcnschen t\u00e4uschen:\u00a0<strong>Kein Kind will jemals eine sexuelle Beziehung zu einem Erwachsenen &#8211; kein einziges, niemals.<\/strong>\u00a0Ein Kind k\u00f6nnte Ihnen sagen, dass es sexuelle Beziehungen haben m\u00f6chte, oder es k\u00f6nnte Angst haben, nein zu sagen, weil es Ihnen gefallen m\u00f6chte. Es k\u00f6nnte den Anschein erwecken, dass es sexuellen Kontakt mit Ihnen sucht, weil es etwas erlebt hat, das es beunruhigt oder beunruhigt. Als Erwachsener oder Jugendlicher ist es Ihre Pflicht, darauf zu reagieren, dass sexuelle oder romantische Beziehungen zu Kindern verboten sind, weil sie Kindern schaden.<\/p>\n<h5>Ich versp\u00fcre den Drang zu masturbieren, wenn ich Bilder von Kindern anschaue<\/h5>\n<p>Die Ausbeutung eines Kindes unter Verwendung seines Bildes ist inakzeptabel. Lassen Sie sich nicht von dem erzwungenen L\u00e4cheln eines Kindes t\u00e4uschen, das von Erwachsenen manipuliert wurde. Wenn Sie zu diesen Bildern masturbieren, machen Sie sich zu einem Komplizen der sexuellen Ausbeutung ihres Bildes.\u00a0<strong>Es besteht eine sehr reale Gefahr der Abh\u00e4ngigkeit und Isolation.<\/strong><\/p>\n<h5>Ich w\u00fcnschte, ich w\u00fcrde mich nicht mehr zu Kindern hingezogen f\u00fchlen<\/h5>\n<p>Auch wenn Sie sich im Moment ein Leben ohne die Anziehung zu Kindern nicht vorstellen k\u00f6nnen, sollten Sie wissen, dass es vielen Menschen gelungen ist, ihren Drang mit fachlicher Hilfe zu \u00fcberwinden oder zu kontrollieren. Diese Anziehungskraft muss nicht Ihr ganzes Leben bestimmen.\u00a0<strong>Das Wichtigste ist, dass Sie sich nicht mit Ihren Trieben isolieren.<\/strong>\u00a0oder sich in einer beunruhigenden Fantasie zu verfangen, oder zu glauben, dass man zu einer lebenslangen Haftstrafe ohne erf\u00fcllte Sexualit\u00e4t verurteilt ist.<\/p>\n<hr \/>\n<h4>P\u00e4dophilie<\/h4>\n<h6>Was ist P\u00e4dophilie und wer ist ein P\u00e4dophiler?<\/h6>\n<p>P\u00e4dophile k\u00f6nnen Jugendliche oder Erwachsene jeden Geschlechts sein, die sich sexuell zu vorpubert\u00e4ren Kindern (d. h. zu Kindern, die noch nicht in der Pubert\u00e4t sind) oder zu Kindern, die gerade erst mit der pubert\u00e4ren Entwicklung begonnen haben, hingezogen f\u00fchlen. Nach den diagnostischen Kriterien sind in der Regel Kinder unter 13 Jahren betroffen.<br \/>\nEinige P\u00e4dophile f\u00fchlen sich nur zu M\u00e4dchen hingezogen, andere nur zu Jungen. Manche f\u00fchlen sich zu beidem hingezogen, und manche f\u00fchlen sich gleicherma\u00dfen zu Kindern und Jugendlichen oder Erwachsenen hingezogen.<br \/>\nP\u00e4dophilie gibt es weltweit und quer durch alle sozialen, kulturellen und wirtschaftlichen Schichten. Nur weil niemand dar\u00fcber spricht, hei\u00dft das nicht, dass es sie nicht gibt!<br \/>\nNiemand entscheidet sich daf\u00fcr, diese Anziehungskraft zu erleben, und\u00a0<strong>die Mehrheit der P\u00e4dophilen wird niemals ein Kind missbrauchen<\/strong>.<br \/>\nNiemand ist f\u00fcr die unerw\u00fcnschten Gedanken verantwortlich, die in seinem Kopf auftauchen, aber jeder ist f\u00fcr sein Handeln verantwortlich. Jedes Verhalten, das die intimen oder sexuellen Grenzen eines Kindes \u00fcberschreitet, ist streng verboten. Dazu geh\u00f6ren romantische Absichten, anz\u00fcgliche Bemerkungen, das Zeigen von unangemessenem Material, das Entbl\u00f6\u00dfen oder das Einbeziehen eines Kindes in jegliche Form von sexuellem Verhalten von Erwachsenen.<\/p>\n<h6>Warum ist P\u00e4dophilie so be\u00e4ngstigend?<\/h6>\n<p>P\u00e4dophilie wird oft f\u00e4lschlicherweise als der sexuelle Missbrauch von Kindern definiert. In Wirklichkeit ist P\u00e4dophilie keine Handlung, sondern eine sexuelle Anziehung.<br \/>\nMenschen mit dieser Anziehungskraft sind nicht von Natur aus gef\u00e4hrlich oder moralisch defekt. Sie sind oft Menschen, die Schmerzen haben und Hilfe brauchen, um mit ihren Gedanken fertig zu werden oder ihre Fantasien auszuleben, ohne ein Kind zu verletzen.<\/p>\n<h6>Warum wird jemand zu einem P\u00e4dophilen?<\/h6>\n<p>Die Gr\u00fcnde daf\u00fcr sind vielf\u00e4ltig und h\u00e4ngen von der pers\u00f6nlichen Geschichte jedes Einzelnen ab. Einige P\u00e4dophile haben in ihrer Kindheit Gewalt erlebt, die sexueller Natur gewesen sein kann oder auch nicht. Andere waren in der Zeit, in der sie ihre eigene Sexualit\u00e4t erkundeten, zutiefst gest\u00f6rt, und wieder andere sind vielleicht in Familien aufgewachsen, in denen die Grenzen der Intimit\u00e4t unklar oder schlecht definiert waren.<\/p>\n<h6>Einmal ein P\u00e4dophiler, immer ein P\u00e4dophiler?<\/h6>\n<p>Die Erfahrung dieser Anziehung kann sehr belastend sein, aber sie ist kein lebenslanges Urteil. Manche Menschen f\u00fchlen sich nicht mehr zu Kindern hingezogen, nachdem sie eine Therapie oder Unterst\u00fctzung durch einen Spezialisten erhalten haben. Andere lernen, mit solchen Fantasien zu leben, ohne das Gef\u00fchl zu haben, dass sich diese Fantasien auf ihr t\u00e4gliches Leben auswirken.<\/p>\n<h6>Ist es wahr, dass ein Erwachsener romantische Gef\u00fchle f\u00fcr ein Kind empfinden kann?<\/h6>\n<p>Ein Jugendlicher oder Erwachsener kann Gef\u00fchle der Liebe f\u00fcr ein Kind empfinden, aber dies sollte niemals zu einer sexuellen Beziehung f\u00fchren, denn es ist unm\u00f6glich, Liebe und sexuelles Verlangen mit Kindern zu teilen. Das liegt daran, dass Kinder noch nicht reif genug sind, um diese Dinge zu verstehen, und eine sexuelle Beziehung ist immer sch\u00e4dlich f\u00fcr ein Kind, selbst wenn es Z\u00e4rtlichkeit, Liebe und Sanftheit gibt. Wenn eine pubertierende Person sexuelles Verlangen gegen\u00fcber einer viel j\u00fcngeren vorpubert\u00e4ren Person versp\u00fcrt, sollte sie sich immer distanzieren und Hilfe suchen, denn das ist ein Zeichen f\u00fcr ein Problem.<\/p>\n<h6>Tr\u00e4gt die Gesellschaft zu sch\u00e4dlichen Einstellungen bei, wenn sie Kinder sexualisiert?<\/h6>\n<p>Unsere Gesellschaft sollte weder Kinder erotisieren (Kindersch\u00f6nheitswettbewerbe, Kleidung im Stil von Erwachsenen oder starkes Make-up bei kleinen Kindern &#8230;) noch Erwachsene infantilisieren (vorpubert\u00e4re K\u00f6rperformen, fehlende K\u00f6rperbehaarung als Standard &#8230;)<br \/>\nUnsere Gesellschaft hindert Kinder daran, Kinder zu sein, und Erwachsene daran, Erwachsene zu sein, wenn sie die Unterschiede zwischen den Generationen verwischt, und das f\u00fchrt zu einer gro\u00dfen Verwirrung, die manchmal zu sexuellen \u00dcbergriffen auf Kinder f\u00fchren kann.<br \/>\nEin kleines M\u00e4dchen, das wie eine sexy Frau gekleidet ist (in engen Kleidern, Minir\u00f6cken, kurzen Shorts, Bikini &#8230;), kann uns zutiefst beunruhigen; wenn es jedoch sexuelle Erregung ausl\u00f6st, sollten Sie dies zur Kenntnis nehmen und sich bewusst sein, dass es nur so tut, als sei es erwachsen, und dass es noch ein Kind ist. Ihre Kleidung oder ihr Verhalten ist niemals eine Einladung oder ein Ausdruck sexueller Absichten.<\/p>\n<h6>Besteht ein Risiko, wenn man sich Fotos oder Videos von nackten Kindern ansieht?<\/h6>\n<p>Der Konsum von sexualisierten Bildern mit Minderj\u00e4hrigen trainiert das Gehirn darauf, Erregung mit unangemessenem Material zu assoziieren, und kann schnell in ein zwanghaftes Muster \u00fcbergehen. Mit der Zeit m\u00fcssen Sie immer mehr dieser Bilder sehen, um sich selbst zu erregen, und schon bald werden Sie das Bed\u00fcrfnis haben, Bilder von nackten Kindern in eindeutigen Posen oder von sexuellen \u00dcbergriffen zu sehen.<br \/>\nDas Betrachten von Material \u00fcber sexuellen Kindesmissbrauch (Kinderpornografie, p\u00e4dosexuelle Inhalte, Kinderpornografie &#8230;) macht Sie zu einem Komplizen der Angriffe, denen diese Kinder bei der Herstellung solcher Bilder oder Filme ausgesetzt sind. Wenn Sie diese Bilder ansehen &#8211; auch wenn Sie nicht daf\u00fcr bezahlen und sie nicht weitergeben &#8211; sind Sie an einem Wirtschaftssystem beteiligt, das die Produktion dieser Bilder und damit aggressive Handlungen gegen\u00fcber weiteren Kindern f\u00f6rdert.<br \/>\nIn fast allen L\u00e4ndern ist es illegal, kinderpornografische Bilder herzustellen, zu verbreiten oder anzusehen, und die Strafen daf\u00fcr sind hart!<br \/>\nDamit sind sehr viele Risiken verbunden: Verhaftung durch die Polizei, Abh\u00e4ngigkeit von solchen Bildern, Anstiftung zur Reproduktion dieser \u00dcbergriffe auf Kinder in Ihrem unmittelbaren Umfeld &#8230;<br \/>\nAls je je verstrikt voelt door deze beelden, moet je snel de hulp van een specialist inroepen om je te helpen er vanaf te komen. Je moet kinderen in deze beelden altijd zien voor wat ze zijn: uitgebuite slachtoffers die iets traumatisch en pijnlijks meemaken, zelfs als dat niet meteen duidelijk is.<br \/>\n<strong>Auch wenn es un\u00fcberwindbar scheint, m\u00fcssen Sie die Kraft und den Mut aufbringen, diese Bilder nicht mehr anzusehen.<\/strong><\/p>\n<h6>Wo findet man Hilfe?<\/h6>\n<p>F\u00fchlen Sie sich zu Kindern hingezogen?<br \/>\nEs ist keine Schande, um Hilfe zu bitten &#8211; im Gegenteil, es ist ein Zeichen von Tapferkeit!<br \/>\nIn vielen L\u00e4ndern gibt es Einrichtungen und Vereinigungen, in denen Fachleute zusammenarbeiten, die Menschen, die sich ungewollt zu Kindern hingezogen f\u00fchlen, dabei helfen, mit ihren Fantasien besser umzugehen und ihre Triebe besser zu kontrollieren.\u00a0<a href=\"https:\/\/vivotis.com\/de\/pedohelp\/#help\"><strong><u>Hilfe finden \u00bb<\/u><\/strong><\/a><br \/>\nWenn es in Ihrem Land keinen spezialisierten Dienst gibt, h\u00e4ngt es von den \u00f6rtlichen kulturellen, beruflichen und rechtlichen Gegebenheiten ab, ob Sie gefahrlos einen Therapeuten aufsuchen k\u00f6nnen. In einigen L\u00e4ndern k\u00f6nnen ausgebildete Therapeuten Menschen, die mit belastenden Gedanken oder Gef\u00fchlen zu k\u00e4mpfen haben, vertrauliche Hilfe anbieten. In anderen L\u00e4ndern ist dies m\u00f6glicherweise nicht m\u00f6glich. Jede Person muss selbst beurteilen, was in ihrem Umfeld angemessen und sicher ist.<br \/>\nEinige Therapeuten verweisen Sie vielleicht an Kollegen, die besser geeignet sind, Ihnen zu helfen, w\u00e4hrend andere ihre T\u00fcren schlie\u00dfen, ohne Ihnen zu helfen, aber verlieren Sie niemals die Hoffnung!<\/p>\n<h6>Was soll ich tun, wenn ich glaube, dass jemand, den ich kenne, mit dieser Anziehung zu k\u00e4mpfen hat?<\/h6>\n<p>Sie k\u00f6nnen in aller Ruhe mit dieser Person sprechen, ohne sie zu verurteilen. Sagen Sie ihr, was Sie gesehen und gef\u00fchlt haben, und ermutigen Sie sie, sich von einem kompetenten Spezialisten helfen zu lassen.<br \/>\nSie k\u00f6nnen auch das Projekt PedoHelp\u2122 erw\u00e4hnen, das Beratung und Informationen bietet.<\/p>\n<hr \/>\n<h4>Zum sexuellen Missbrauch von Kindern<\/h4>\n<h6>Was ist sexueller Missbrauch?<\/h6>\n<p>Gewalt liegt vor, wenn eine Person einer anderen Person sexuelle Absichten oder Verhaltensweisen aufzwingt, entweder weil die andere Person nicht zugestimmt hat oder weil sie nicht in der Lage ist, dies zu verstehen (z. B. ein Kind oder ein Jugendlicher).<br \/>\nKinder sind nicht in der Lage, einer sexuellen Handlung zuzustimmen, weil sie noch nicht wissen, was das ist, und sie m\u00fcssen es auch nicht wissen. Sie sind zu jung und entwicklungsm\u00e4\u00dfig noch nicht bereit, Sexualit\u00e4t zu verstehen oder sich damit auseinanderzusetzen.<br \/>\nEin Kind in eine Situation zu bringen, die ihm eine sexuelle Bedeutung oder einen sexuellen Kontext verleiht, selbst wenn dies im Rahmen eines Spiels geschieht, bedeutet, dieses Kind zu einem Objekt der Befriedigung der eigenen erwachsenen oder jugendlichen Begierde zu machen, und das ist inakzeptabel.<\/p>\n<h6>Wer sind die Straft\u00e4ter?<\/h6>\n<p>Bei den T\u00e4tern kann es sich um M\u00e4nner oder Frauen, Jugendliche oder Erwachsene handeln, die sich zu Kindern hingezogen f\u00fchlen k\u00f6nnen oder auch nicht. Einige T\u00e4ter sind p\u00e4dophil (f\u00fchlen sich zu Kindern hingezogen), aber die meisten sind es nicht.<br \/>\nWir stellen uns Missbrauchst\u00e4ter oft als sadistisch, pervers, manipulativ und berechnend vor. Solche Menschen gibt es zwar, aber sie sind tats\u00e4chlich sehr selten. Die \u00fcberwiegende Mehrheit der sexuellen Kindersch\u00e4nder sind liebevolle und f\u00fcrsorgliche Menschen, die Kinder wirklich lieben. Au\u00dferdem erscheinen sie Kindern und Eltern oft vertrauensw\u00fcrdig.<br \/>\nDie meisten T\u00e4ter, die solche Anziehungskr\u00e4fte versp\u00fcren, haben nie Hilfe gesucht oder vor der Tat \u00fcber ihre Gedanken gesprochen.<\/p>\n<h6>Wer sind die Opfer?<\/h6>\n<p>Jedes Kind kann Opfer von sexuellem Missbrauch werden.<br \/>\nKinder mit guten psychosozialen F\u00e4higkeiten, die verstehen, was erlaubt ist und was nicht, und die die Grundregeln der pers\u00f6nlichen Grenzen kennen, sind jedoch besser in der Lage, Kinder, Jugendliche und Erwachsene zu erkennen, die ihnen Unbehagen bereiten, und sich zu trauen, Nein zu sagen. Wenn diese Kinder mit einer problematischen Situation konfrontiert werden, sind sie auch eher in der Lage, einen Erwachsenen um Hilfe zu bitten.<br \/>\nEinsame Kinder, die sich selbst \u00fcberlassen sind, und solche, denen es an Orientierung in ihren Beziehungen zu anderen fehlt (schwache psychosoziale F\u00e4higkeiten) oder die die Regeln der Intimit\u00e4t nicht verstanden haben (Familien mit unklaren oder unangemessenen Grenzen), werden h\u00e4ufiger Opfer sexueller Gewalt als andere.<\/p>\n<h6>Was sind die Folgen des sexuellen Missbrauchs f\u00fcr ein Kind?<\/h6>\n<p>Sexuelle \u00dcbergriffe haben oft schwerwiegende Folgen, unabh\u00e4ngig vom Alter des Opfers. Die Folgen sind je nach Kind, Art des Missbrauchs, seiner H\u00e4ufigkeit, der Beziehung zum T\u00e4ter und der therapeutischen und rechtlichen Unterst\u00fctzung nach dem \u00dcbergriff unterschiedlich.<br \/>\nDie Nachwirkungen treten oft in unterschiedlicher Weise und zu verschiedenen Zeiten des Lebens auf.<br \/>\nAbgesehen von den m\u00f6glichen k\u00f6rperlichen oder medizinischen Folgen kann ein Kind unter zahlreichen psychologischen Folgen leiden, wie Schuld und Scham, Furcht, Angst, Wut, Verlust des Selbstvertrauens, Depressionen, Angstattacken, chronischen Schmerzen, sozialer Isolation, Misstrauen gegen\u00fcber allen Jugendlichen und\/oder Erwachsenen, Schwierigkeiten beim Aufbau gesunder intimer Beziehungen, Ged\u00e4chtnis- oder Konzentrationsst\u00f6rungen, Schlafst\u00f6rungen oder Essst\u00f6rungen&#8230;<br \/>\n\u00dcbergriffe k\u00f6nnen auch zu destruktivem Verhalten f\u00fchren: Selbstmordversuche, Selbstverst\u00fcmmelung, Magersucht\/Bulimie, Prostitution, Straff\u00e4lligkeit, Risikoverhalten und Abh\u00e4ngigkeiten (von Alkohol, Drogen oder anderen Substanzen)&#8230;<br \/>\nSexueller Missbrauch kann das Risiko sp\u00e4terer Schwierigkeiten, einschlie\u00dflich unangemessener Verhaltensweisen, erh\u00f6hen, obwohl dies nicht unvermeidlich ist.<br \/>\nSchweigen ist nicht unvermeidlich, und auch das Leiden ist nicht unvermeidlich. Es ist m\u00f6glich, sich zu erholen und sein Leben mit Hilfe eines qualifizierten Spezialisten wieder aufzubauen.<\/p>\n<hr \/>\n<h4>Zum Sextourismus mit Kindesmissbrauch<\/h4>\n<h6>Welche Kinder sind Opfer von Sextourismus?<\/h6>\n<p>Die Opfer der Kinderprostitution sind sowohl M\u00e4dchen als auch Jungen. Sie kommen h\u00e4ufig aus benachteiligten sozialen Verh\u00e4ltnissen. Sextourismus mit Kindern ist ein wachsendes Ph\u00e4nomen.<br \/>\nWenn Sie Zeuge eines Falles von Sextourismus mit Minderj\u00e4hrigen in Ihrem Land oder im Ausland werden, melden Sie ihn sofort.<\/p>\n<h6>Was sind die Risiken?<\/h6>\n<p>Sextouristen kommen aus allen Schichten. Sie k\u00f6nnen verheiratet oder ledig, m\u00e4nnlich oder weiblich, reich oder arm, jung oder alt sein. Sextouristen, die Kinder missbrauchen, k\u00f6nnen in ihrem Herkunftsland strafrechtlich verfolgt werden, wenn sie in dem Land, in dem die Straftat begangen wurde, nicht belangt wurden. Die Risiken sind enorm: eine mehrj\u00e4hrige Haftstrafe und sehr hohe Geldstrafen &#8211; auch noch viele Jahre nach dem Missbrauch. Verurteilungen k\u00f6nnen sich aus der Prostitution von Minderj\u00e4hrigen ergeben, aber auch aus sexueller N\u00f6tigung, Vergewaltigung, sexuellen Darstellungen von Kindern und anderen Straftaten oder versuchten Straftaten gegen die Integrit\u00e4t von Kindern.<\/p>\n<h6>Tr\u00e4gt der Sextourismus zur wirtschaftlichen Entwicklung eines Landes bei?<\/h6>\n<p>Touristen, die ein Land besuchen, um Menschen f\u00fcr ihr sexuelles Vergn\u00fcgen zu benutzen, f\u00f6rdern nur die Korruption in diesem Land und die Ausbeutung und Entw\u00fcrdigung seiner Bev\u00f6lkerung.<\/p>\n<h6>Ist es in Asien Tradition, Sex mit Kindern zu haben?<\/h6>\n<p>In einigen L\u00e4ndern veranlasst extreme Armut die Eltern, ihre Kinder in die Prostitution zu treiben. Menschenhandelsnetze nutzen Kinder in prek\u00e4ren Situationen aus, um sich zu bereichern, und andere Menschen nutzen das Elend aus, um diese Kinder zu Sexsklaven zu machen.<br \/>\nIn einigen Regionen gibt es sch\u00e4dliche Mythen, die besagen, dass der Kontakt mit einem Minderj\u00e4hrigen Krankheiten heilen kann. In Wirklichkeit ist das Gegenteil der Fall: Sexuelle Beziehungen mit Kindern bergen ein hohes Risiko der \u00dcbertragung von Infektionen, einschlie\u00dflich HIV. Sehr oft sind die Minderj\u00e4hrigen, die in solchen Situationen ausgebeutet werden, nicht \u00fcber die M\u00f6glichkeiten der Pr\u00e4vention und des Schutzes vor sexuell \u00fcbertragbaren Krankheiten informiert.<br \/>\nUnabh\u00e4ngig von Land, Kultur, Tradition oder Glauben sucht ein Kind niemals nach sexuellen Aktivit\u00e4ten oder willigt in diese ein.<\/p>\n<hr \/>\n<h4>Bei Kindern<\/h4>\n<h6>Was ist ein inzestu\u00f6ses famili\u00e4res Umfeld?<\/h6>\n<p>In einem inzestu\u00f6sen Familienumfeld sind die normalen Grenzen zwischen den Generationen verwischt oder aufgehoben. Rollen, Freir\u00e4ume und Privatsph\u00e4re werden nicht respektiert, und die Beziehungen werden in einer Weise verwirrt, die die emotionalen und entwicklungsbezogenen Bed\u00fcrfnisse des Kindes verletzt.<br \/>\nIn manchen Situationen kann dieses Umfeld auch illegale oder sch\u00e4dliche Verhaltensweisen zwischen Familienmitgliedern beinhalten. In allen F\u00e4llen, in denen ein Kind involviert ist, ist dies sch\u00e4dlich und f\u00fchrt zu ernsthafter Verwirrung \u00fcber Identit\u00e4t, Autonomie und pers\u00f6nliche Grenzen. Kinder, die in einem solchen Umfeld aufwachsen, haben m\u00f6glicherweise Schwierigkeiten, die Grenzen zu verstehen, die sie selbst und andere sch\u00fctzen, und k\u00f6nnen sp\u00e4ter unangemessene Verhaltensweisen wiederholen, ohne zu erkennen, dass andere nicht dieselben Erwartungen oder Erfahrungen teilen.<\/p>\n<h6>Kann ein Kind Verlangen und sexuelle Lust empfinden?<\/h6>\n<p>Die sich entwickelnde Sexualit\u00e4t von Kindern unterscheidet sich stark von der von Erwachsenen, und es ist wichtig, dass diese beiden Realit\u00e4ten nicht verwechselt werden.<br data-start=\"634\" data-end=\"637\" \/>W\u00e4hrend sie heranwachsen, erforschen Kinder ihren K\u00f6rper und entwickeln Neugierde auf sich selbst. Vielleicht finden sie in dieser Erkundung Trost oder Beruhigung. Ein Kind sollte bei einem solchen privaten Verhalten niemals ermutigt, unter Druck gesetzt, gelenkt oder \u00fcberwacht werden, auch nicht mit Z\u00e4rtlichkeit und Streicheleinheiten.<\/p>\n<h6>Kann ein Kind Interesse an sexuellem Verhalten zeigen?<\/h6>\n<p>Kinder verf\u00fcgen noch nicht \u00fcber die psychologische oder physiologische F\u00e4higkeit, bewusst und wissentlich sexuelle Erfahrungen zu machen. Sie k\u00f6nnen einer \u00e4lteren Person sagen, dass sie neugierig oder interessiert sind, oder sie wagen es nicht, nein zu sagen, weil sie sie gl\u00fccklich machen wollen, aber das bedeutet nicht, dass sie solche Erfahrungen wirklich verstehen oder w\u00fcnschen.<br \/>\nWenn ein Jugendlicher oder ein Erwachsener einem Kind einen sexuellen Akt vorschl\u00e4gt, wei\u00df das Kind nicht, was das ist oder ob es gut oder schlecht f\u00fcr es ist. Es ist zu jung, um dar\u00fcber Bescheid zu wissen, und es kann nicht ja oder nein zu etwas sagen, von dem es nichts wei\u00df. Es ist vielleicht neugierig, aber das bedeutet nicht, dass es einwilligt. Alles hat seine Zeit: Ein Kind wird Sex mit jemandem in seinem Alter entdecken, wenn es \u00e4lter ist.<\/p>\n<h6>Wie sollte ich reagieren, wenn ein Kind sich gegen\u00fcber einer \u00e4lteren Person unangemessen verh\u00e4lt?<\/h6>\n<p>Ein Kind kann durch etwas, das es erlebt, gesehen oder geh\u00f6rt hat, beunruhigt sein und sich einem Jugendlichen oder Erwachsenen n\u00e4hern, um ihm Fragen zu stellen oder sich in einer Weise zu verhalten, die pers\u00f6nliche Grenzen \u00fcberschreitet. Dies ist niemals ein Ausdruck echter Absicht oder Zustimmung, sondern einfach der Ausdruck eines Bed\u00fcrfnisses zu wissen oder zu pr\u00fcfen, was erlaubt ist und was nicht erlaubt ist. Der Jugendliche oder Erwachsene muss immer Grenzen setzen, muss sich immer daran erinnern, was verboten ist, und muss Kinder vor dem sch\u00fctzen, was sie verletzen wird.<\/p>\n<h6>Kann die Sexualit\u00e4t eines Erwachsenen ein Kind beeinflussen oder anregen?<\/h6>\n<p>Die Entdeckung des eigenen K\u00f6rpers und des K\u00f6rpers der anderen ist nur dann ein angenehmes Spiel, wenn es zwischen Kindern gleichen Alters und gleicher Reife stattfindet, die sich auf das Spiel einlassen. Erwachsene m\u00fcssen eingreifen, wenn ein Kind einem anderen Kind diese Art von Spiel aufzwingt oder wenn es zu problematischen sexuellen Verhaltensweisen kommt.<br \/>\nEs ist zwar wichtig, zu versuchen, die Neugier und die Fragen von Kindern zum Thema Sexualit\u00e4t zu beantworten, wenn n\u00f6tig mit Hilfe von altersgerechten B\u00fcchern, aber dies sollte immer auf ihre Fragen und ihre F\u00e4higkeit zu verstehen beschr\u00e4nkt bleiben. Es ist immer unangemessen und sch\u00e4dlich, ein Kind in ein Verhalten mit sexueller Bedeutung zu verwickeln, sei es durch k\u00f6rperlichen Kontakt, Aufforderungen oder das Anschauen von explizitem Material. Keine sexuelle Handlung mit einem Kind kann als lehrreich angesehen werden.<\/p>\n<h6>Was ist zu tun, wenn ein Kind ein pornografisches Bild sieht?<\/h6>\n<p>Je nach Alter und Kenntnisstand der Kinder k\u00f6nnen Sie ihnen erkl\u00e4ren, dass Pornografie etwas ganz anderes ist als echte Beziehungen oder Intimit\u00e4t. Genau wie im Kino, wo die Schauspieler vorgeben, andere zu verletzen oder starke Emotionen zu zeigen, geben professionelle Schauspieler vor, in pornografischen Bildern Vergn\u00fcgen zu haben. Ihre Bewegungen sind abrupt, und ihre Posen sind rein auf visuelle Wirkung und nicht auf Authentizit\u00e4t ausgelegt. Schauspielerinnen und Schauspieler nehmen oft Drogen, um effektiver zu sein, und unterziehen sich h\u00e4ufig plastischen Operationen, um ihren K\u00f6rper zu ver\u00e4ndern. Manchmal werden ihre K\u00f6rperhaare rasiert, und Make-up und Beleuchtung werden eingesetzt, um Pickel, Narben oder die nat\u00fcrliche Hautfarbe zu verdecken. Pornografie zeigt Sex, nicht eine liebevolle sexuelle Beziehung.<\/p>\n<h6>Bedeutet der Beginn der Menstruation, dass ein M\u00e4dchen bereit f\u00fcr intime Beziehungen ist?<\/h6>\n<p>M\u00e4dchen brauchen ebenso wie Jungen eine gewisse Zeit nach Beginn der Pubert\u00e4t, bevor sie bereit sind, Sex zu haben, denn Sexualit\u00e4t ist sowohl physisch als auch psychisch.<br \/>\nJugendliche in eine Ehe oder intime Beziehung zu zwingen, nur weil sie biologisch fortpflanzungsf\u00e4hig sind, ist missbr\u00e4uchlich und sch\u00e4dlich f\u00fcr ihre Entwicklung und ihr k\u00fcnftiges Leben.<\/p>\n<h6>Wie k\u00f6nnen Kinder f\u00fcr die Gefahr des sexuellen Missbrauchs sensibilisiert werden?<\/h6>\n<p>Eine dem Alter und Entwicklungsstand der Kinder angepasste Sexualerziehung hilft ihnen, gute psychosoziale Kompetenzen zu entwickeln.<br \/>\nKinder m\u00fcssen in der Lage sein, die verschiedenen Teile des K\u00f6rpers zu benennen, einschlie\u00dflich privater Bereiche wie Penis, Vulva und Anus, und zwar mit Worten, die sie sich nicht scheuen, vor Erwachsenen auszusprechen. Diese Begriffe sind anatomisch und angemessen und sollten niemals als schmutzig oder besch\u00e4mend angesehen werden.<br \/>\nKinder m\u00fcssen lernen, private und pers\u00f6nliche Bereiche zu erkennen, um diese Bereiche am eigenen K\u00f6rper und an denen anderer zu respektieren.<br \/>\nKinder m\u00fcssen wissen, dass sie sich Erwachsenen anvertrauen k\u00f6nnen und dass sie ein offenes Ohr f\u00fcr sie haben.<\/p>\n<h6>Sollten wir mit Kindern sprechen, wenn jemand, der ihnen nahe steht, sexuell missbraucht worden ist?<\/h6>\n<p>Es ist die Aufgabe der Erwachsenen, Kinder zu sch\u00fctzen, aber wenn Kinder aus irgendeinem Grund mit einer Person allein sind, die sie angreifen k\u00f6nnte, m\u00fcssen sie gewarnt werden, um sich zu sch\u00fctzen.<br \/>\nIn anderen F\u00e4llen m\u00fcssen Sie die Fragen Ihrer Kinder beantworten und dabei ber\u00fccksichtigen, was sie wissen wollen und wie alt sie sind. Ein dunkles Familiengeheimnis ist sch\u00e4dlich f\u00fcr die Entwicklung eines Kindes, aber auch eine verfr\u00fchte Enth\u00fcllung ist sch\u00e4dlich. Z\u00f6gern Sie nicht, die Hilfe eines Therapeuten in Anspruch zu nehmen, der Sie anleitet und begleitet.<\/p>\n<h6>Woran erkenne ich ein Opfer von sexuellem Kindesmissbrauch?<\/h6>\n<p>Kinder haben oft nicht das Wissen, die Erfahrung oder die Worte, um auszudr\u00fccken, was sie erlebt oder erlitten haben, weil die Sexualit\u00e4t f\u00fcr sie eine unbekannte Welt ist. Deshalb dr\u00fccken sie ihr Leid und ihre Unzufriedenheit mit ihrem K\u00f6rper aus.<br \/>\nJede pl\u00f6tzliche Ver\u00e4nderung des Verhaltens oder des Aussehens sollte Erwachsene dazu veranlassen, die Ursache f\u00fcr diese Ver\u00e4nderung zu hinterfragen.<br \/>\nWenden Sie sich im Zweifelsfall an eine Fachkraft, die dem Kind Fragen stellen kann, ohne seine Antworten zu beeinflussen.<br \/>\nWenn Sie den Verdacht haben, dass ein Kind missbraucht worden ist, sollten Sie dies sofort melden.<\/p>\n<h6>Was ist das Beste, was man tun kann, wenn ein Kind missbraucht worden ist?<\/h6>\n<p>Bleiben Sie zun\u00e4chst einmal ruhig.<br \/>\nGlauben Sie den Kindern, helfen Sie ihnen, sich mit ihren eigenen Worten auszudr\u00fccken, ohne etwas hinzuzuf\u00fcgen und ohne sich von Ihren Sorgen, Ihrer Fantasie und Ihrem Wissen \u00fcber Sexualit\u00e4t \u00fcberw\u00e4ltigen zu lassen. Bitten Sie sie nicht, sich zu wiederholen oder Ihnen wiederholt zu erz\u00e4hlen, was sie erlebt haben.<br \/>\nBringen Sie sie umgehend zu den zust\u00e4ndigen Beh\u00f6rden oder Diensten (z. B. Polizei oder Kinderschutz), damit sie von geschulten Fachleuten unterst\u00fctzt werden, die ihre Aussagen aufnehmen.<br \/>\nErlauben Sie geschulten Fachleuten die Durchf\u00fchrung von Befragungen und Untersuchungen.<br \/>\nSorgen Sie sich um das Wohlergehen der Kinder und ihren Schutz, ohne jemals zu versuchen, selbst f\u00fcr Gerechtigkeit zu sorgen.<br \/>\nWenn Sie Zweifel haben oder sich die Kinder nicht klar ausdr\u00fccken, k\u00f6nnen Sie mit ihnen einen Kindertherapeuten aufsuchen.<br \/>\nSagen Sie den Kindern auf jeden Fall, dass es richtig war, mit Ihnen zu sprechen, loben Sie sie f\u00fcr ihren Mut und danken Sie ihnen, dass sie Ihnen vertraut haben.<br \/>\n<a href=\"https:\/\/childhelplineinternational.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sie k\u00f6nnen die Kinder-Helpline Ihres Landes anrufen, um eine Meldung zu machen.<\/a><\/p>\n<h6>Was ist, wenn Ihr Kind oder Jugendlicher sich gegen\u00fcber einem anderen Kind sexuell verletzend verhalten hat?<\/h6>\n<p>Wenn Ihre Kinder ein anderes Kind missbraucht haben, kann es sein, dass sie selbst Dinge erlebt, gesehen oder geh\u00f6rt haben, die ihr emotionales oder entwicklungsbedingtes Wohlbefinden gest\u00f6rt haben. Bieten Sie ihnen die M\u00f6glichkeit an, mit einem Kindertherapeuten zu sprechen und sie zu begleiten, wenn sie damit einverstanden sind.<br \/>\nEs w\u00e4re auch ratsam, einen Therapeuten zu konsultieren &#8211; entweder allein, in Begleitung Ihres Partners oder gemeinsam mit der Familie -, um dar\u00fcber nachzudenken, wie Ihre Familie funktioniert und um zu verstehen, warum Ihre Kinder nicht gelernt haben, was grunds\u00e4tzlich verboten ist.<\/p>\n<hr \/>\n<h4>Therapeuten: Wenn ein Patient \u00fcber eine sexuelle Anziehung zu Minderj\u00e4hrigen berichtet<\/h4>\n<h6>Was ist P\u00e4dophilie?<\/h6>\n<p>P\u00e4dophilie ist eine Paraphilie, die in psychiatrischen Diagnoseklassifikationen anerkannt ist. Die meisten Menschen mit dieser Neigung sind nicht an illegalen oder sch\u00e4dlichen Handlungen beteiligt.<br \/>\nAls Angeh\u00f6riger eines Gesundheitsberufs m\u00fcssen Sie sich in erster Linie die Sorgen Ihres Patienten anh\u00f6ren. Das ist wahrscheinlich der Grund, warum der Patient sich an Sie gewandt hat; au\u00dferdem vertraut er auf Ihre F\u00e4higkeiten und Ihr Wohlwollen.<br \/>\nP\u00e4dophilie bezieht sich auf eine anhaltende sexuelle Anziehung zu vorpubert\u00e4ren Kindern.<br \/>\nP\u00e4dophilie ist ein klinischer Zustand, der im ICD und im DSM, den beiden wichtigsten internationalen Diagnosesystemen, klassifiziert ist.<br \/>\nIm ICD wird P\u00e4dophilie unter den St\u00f6rungen der Sexualpr\u00e4ferenz aufgef\u00fchrt und definiert als \u201ceine sexuelle Vorliebe f\u00fcr Kinder, Jungen oder M\u00e4dchen oder beides, in der Regel im vorpubert\u00e4ren oder fr\u00fchpubert\u00e4ren Alter\u201d.\u201d<br \/>\nIm DSM wird die p\u00e4dophile St\u00f6rung als eine paraphile St\u00f6rung eingestuft. Sie bezieht sich auf ein wiederkehrendes und anhaltendes sexuelles Interesse an vorpubert\u00e4ren Kindern, das mindestens sechs Monate andauert, ein Kind im Allgemeinen im Alter von 13 Jahren oder j\u00fcnger betrifft und zu erheblichem Leid, Beeintr\u00e4chtigung oder dem Risiko eines sch\u00e4dlichen Verhaltens f\u00fchrt.<br \/>\nP\u00e4dophile Anziehung ist kein einheitlicher Zustand. In den klinischen Beschreibungen werden verschiedene Muster unterschieden: Sie kann exklusiv oder nicht exklusiv sein, sich auf M\u00e4dchen, Jungen oder beides richten, und die Betroffenen k\u00f6nnen abstinent sein oder ein unterschiedlich hohes Risiko aufweisen. Diese Unterschiede beschreiben nur die klinische Darstellung und verringern nicht die rechtliche Verantwortung f\u00fcr sch\u00e4dliche Handlungen.<br \/>\nSchlie\u00dflich k\u00f6nnen Personen mit dieser Anziehungskraft abstinent bleiben, oder sie k\u00f6nnen ein unterschiedliches Ma\u00df an Verhaltensrisiken aufweisen.<\/p>\n<h6>Wie wird man ein P\u00e4dophiler?<\/h6>\n<p>Es gibt umfangreiche Literatur \u00fcber Personen, die Straftaten an Minderj\u00e4hrigen begehen, ihre Vorgeschichte und Begleiterkrankungen; es gibt jedoch nur wenige Daten \u00fcber die Entwicklung dieser Anziehungskraft bei Personen, die nie danach gehandelt haben. Wir haben jedoch festgestellt, dass es nicht sinnvoll ist, beide St\u00f6rungen systematisch zu verwechseln.<br \/>\nAu\u00dferdem bleibt das Konstrukt jeder Art von sexueller Pr\u00e4ferenz aufgrund seiner Komplexit\u00e4t und der Kombination verschiedener Aspekte \u201cr\u00e4tselhaft\u201d. Neben unbestreitbaren individuellen Umst\u00e4nden sollten wir bei der Sexualisierung von Kindern auch gesellschaftliche Faktoren nicht vergessen (z. B. hypersexualisierte Darstellungen in den Medien).<\/p>\n<h6>Ist mein Patient \u2018gef\u00e4hrlich\u2019?<\/h6>\n<p><strong>Gibt es Fr\u00fchwarnzeichen, bevor die Tat begangen wird?<\/strong><br \/>\nAus psychopathologischer Sicht ist jede Gefahr zun\u00e4chst eine Anf\u00e4lligkeit. Ein Patient, der sich einer Therapie unterzieht, hat ein geringeres Risiko, ein sch\u00e4dliches Verhalten an den Tag zu legen. Als Angeh\u00f6rige der Gesundheitsberufe m\u00fcssen wir uns zun\u00e4chst um diese Anf\u00e4lligkeit k\u00fcmmern. Wenn die therapeutische Verbindung stark ist, ist es kein Tabu, dem Patienten die Frage nach sch\u00e4dlichem Verhalten zu stellen. Der Patient kann dann verstehen, dass Sie hier sind, um zu helfen, und dass es eine Alternative zu einer unumkehrbaren Handlung gibt.<br \/>\nHinweis: Entgegen der landl\u00e4ufigen Meinung ist die Verwendung von Material \u00fcber sexuellen Kindesmissbrauch (CSAM) nicht notwendigerweise der erste Schritt zu einem sch\u00e4dlichen Verhalten gegen\u00fcber einem Minderj\u00e4hrigen. Studien \u00fcber den Einfluss von Gewaltbildern im Allgemeinen f\u00fchren nicht zu definitiven und eindeutigen Schlussfolgerungen. In einigen F\u00e4llen kann der Konsum solcher Bilder helfen, belastende Impulse zu bew\u00e4ltigen, w\u00e4hrend er in anderen F\u00e4llen die Auspr\u00e4gung sexueller Fantasien erleichtert. Au\u00dferdem sind nicht alle Konsumenten von P\u00e4do-Pornografie p\u00e4dophil&#8230;<\/p>\n<h6><strong>Gibt es eine Heilung f\u00fcr P\u00e4dophilie? Welche Rolle habe ich als Angeh\u00f6riger eines Gesundheitsberufs?<\/strong><\/h6>\n<p>Das erste Schl\u00fcsselelement besteht darin, dass Sie unabh\u00e4ngig von Ihren Kenntnissen der Materie die Geschichte Ihres Patienten und gegebenenfalls seinen Schmerz und seine \u00c4ngste aufnehmen und dabei sicherstellen, dass Ihre (manchmal negativen) Wahrnehmungen Ihre F\u00e4higkeit zum Zuh\u00f6ren und Ihr Wohlwollen nicht beeintr\u00e4chtigen.<br \/>\nEs gibt spezifische therapeutische Strategien, und es ist wichtig, dass Sie Ihren Patienten dar\u00fcber informieren: analytische oder kognitiv-behaviorale Psychotherapie, sexologische Ans\u00e4tze, medikament\u00f6se Therapie usw. Je nach Ihren Ressourcen und M\u00f6glichkeiten k\u00f6nnen Sie den Patienten entweder an einen Therapeuten oder eine spezialisierte Einrichtung verweisen oder ihn selbst aufnehmen.<br \/>\nDas therapeutische Ziel sollte nicht eine Heilung im Sinne einer Ver\u00e4nderung der sexuellen Anziehungskraft der Person sein, was wie eine Reaktion auf sozialen Druck klingen w\u00fcrde und an unsere klinischen Grenzen sto\u00dfen w\u00fcrde, sondern vielmehr die Sorge um den Schmerz des Patienten und dessen Ursachen. Denken Sie daran, dass Ihr Patient in den meisten F\u00e4llen die gleichen gesellschaftlichen Vorstellungen von P\u00e4dophilie hat wie Sie selbst!<br \/>\nEs gibt verschiedene Ziele f\u00fcr die therapeutische Betreuung: Bew\u00e4ltigung von Trieben und Emotionen; Behandlung von \u00c4ngsten und\/oder Depressionen und Schw\u00e4chung des Selbstwertgef\u00fchls; Behandlung von Suchtverhalten, unabh\u00e4ngig davon, ob es sich um substanzbedingte oder verhaltensbedingte St\u00f6rungen handelt; Pers\u00f6nlichkeitsst\u00f6rungen (Impulsivit\u00e4t, mangelnde Frustrationstoleranz, Hemmungen usw.), Weiterbehandlung von St\u00f6rungen infolge von Missbrauch oder Vernachl\u00e4ssigung (PTBS usw.), Behandlung von gleichzeitig auftretenden sexuellen oder Beziehungsproblemen. Die Begegnung mit dem Patienten ist von entscheidender Bedeutung, um seine Bed\u00fcrfnisse einzusch\u00e4tzen und angemessene Hilfe anzubieten.<\/p>\n<h6>Gibt es pharmakologische Behandlungen?<\/h6>\n<p>Es ist m\u00f6glich, Nachsorge- oder Psychotherapiesitzungen und Medikamente mit dem Ziel zu kombinieren, Gedanken oder Verhaltensweisen, die mit sch\u00e4dlichen oder unangemessenen sexuellen Impulsen verbunden sind, zu reduzieren und zu kontrollieren. Zuvor muss eine Bewertung vorgenommen werden, und der Patient muss einer solchen Behandlung zustimmen.<br \/>\nJe nach Land sind bestimmte Medikamente f\u00fcr diese Indikation zugelassen. W\u00e4hrend der gesamten Behandlung sind eine vorl\u00e4ufige therapeutische Bewertung sowie eine Beobachtung erforderlich.<br \/>\nEinige Studien verweisen auf die Verschreibung von serotonergen Antidepressiva zur Linderung zwanghafter und \u00e4ngstlicher Verhaltensweisen, die bei einigen P\u00e4dophilen zu beobachten sind, doch darf der Verkauf solcher Medikamente f\u00fcr diese Zwecke nicht zugelassen werden.<br \/>\nAndere psychotrope Behandlungen k\u00f6nnen zur Verbesserung einiger m\u00f6glicher Komorbidit\u00e4ten eingesetzt werden.<br \/>\nWenn Sie mehr \u00fcber den Einsatz pharmakologischer Behandlungen erfahren m\u00f6chten, besuchen Sie bitte\u00a0<a href=\"http:\/\/www.inahta.org\/\" rel=\"noopener\">die Website Ihrer nationalen Gesundheitsbeh\u00f6rde<\/a>.<\/p>\n<h6>Wann muss ich eine Beh\u00f6rde benachrichtigen?<\/h6>\n<p>Die Gesetze sind von Land zu Land unterschiedlich.<br \/>\nAngeh\u00f6rige der Gesundheitsberufe k\u00f6nnen in Abh\u00e4ngigkeit von verschiedenen Kriterien (Beruf, Institution, Auftrag &#8230;) dem Berufsgeheimnis unterliegen.<br \/>\nWenn Sie der Meinung sind, dass eine rechtliche Verpflichtung oder ein Risiko besteht, das eine Offenlegung erfordert, k\u00f6nnen Sie sich an die Polizei und\/oder das Justizsystem Ihres Landes wenden.<\/p>\n<p><small><em>Die franz\u00f6sische F\u00f6deration der CRIAVS hat zur Entwicklung dieser Leitlinien beigetragen.<\/em><\/small><\/p>\n<hr \/>\n<h1>Die Charta<\/h1>\n<p><strong>Kopieren und unterschreiben Sie diese Charta, um sich zu verpflichten, niemals ein Kind zu missbrauchen:<\/strong><\/p>\n<p>Ich habe sexuelle Anziehungskr\u00e4fte, die ich mir nicht ausgesucht habe und f\u00fcr die ich nicht verantwortlich bin.<br \/>\nIch erkenne meine Verantwortung f\u00fcr meine Entscheidungen, meine Worte und mein Handeln an.<br \/>\nIch erkenne an, dass Kinder eigenst\u00e4ndige Menschen sind, die von Erwachsenen abh\u00e4ngig sind und des Schutzes, der F\u00fcrsorge und der R\u00fccksichtnahme bed\u00fcrfen.<br \/>\nIch erkenne an, dass die Sexualit\u00e4t von Kindern nicht mit der Sexualit\u00e4t von Erwachsenen identisch ist.<br \/>\nIch verstehe, dass Kinder noch nicht die k\u00f6rperliche und geistige Reife erreicht haben, um in eine sexuelle Erfahrung einzuwilligen.<br \/>\nIch verstehe, dass sexueller Missbrauch traumatische, schmerzhafte und behindernde Folgen f\u00fcr das Leben eines Kindes hat, unabh\u00e4ngig von seinem Alter.<br \/>\nDeshalb verspreche ich heute und f\u00fcr den Rest meines Lebens, niemals ein Kind zu missbrauchen.<br \/>\nSollte ich eines Tages mit einem Kind zusammen sein und Verlangen nach ihm\/ihr empfinden, verspreche ich, mich von diesem Kind zu trennen oder alles in meiner Macht Stehende zu tun, damit es\/sie nicht unter meinem Verlangen leidet, in welcher Weise auch immer.<br \/>\nIch verspreche, ein Kind niemals zu k\u00fcssen oder zu streicheln, wenn ich Lust auf es habe.<br \/>\nIch verspreche, ein Kind niemals absichtlich einer Situation auszusetzen, die es verst\u00f6ren oder sexuell erregen k\u00f6nnte.<br \/>\nIch verpflichte mich, alles in meiner Macht Stehende zu tun, um mich niemals in eine Situation zu begeben, in der mein Sexualtrieb unter dem Einfluss einer Substanz oder eines medizinischen Zustands diese Verpflichtung zunichte machen k\u00f6nnte.<br \/>\nIch verpflichte mich, diese Verpflichtung jetzt und f\u00fcr immer zu erf\u00fcllen.<\/p>\n<hr \/>\n<p><img decoding=\"async\" src=\"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp\" width=\"130px\" \/><\/p>\n<p><strong>Wir verbreiten das Bewusstsein in der ganzen Welt.<br \/>\n<a href=\"https:\/\/www.paypal.com\/donate\/?hosted_button_id=VGV4ELBJYW95E\" rel=\"noopener\">Unterst\u00fctzen Sie unsere Aktion mit einer Spende.<\/a><\/strong><\/p>\n<p>Das PedoHelp\u2122-Projekt wurde von einer Ethikkommission in Zusammenarbeit mit Partnerorganisationen in mehreren L\u00e4ndern entwickelt, darunter FFCRIAVS, ARTAAS, AIUS, SFSC und SNSC in Frankreich, PREVENSI in Spanien, PROSTASIA in den Vereinigten Staaten und IO-NO! in der Schweiz. Das Projekt wurde vom Lanzarote-Ausschuss des Europarats als \u201cvielversprechende Praxis\u201d anerkannt. Seine Ergebnisse\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=VnoVNhdmRJw\" target=\"_blank\" rel=\"noopener\">wurden ebenfalls vorgestellt<\/a>\u00a0vor dem Informationsausschuss des franz\u00f6sischen Senats.<\/p>\n<p><small>PedoHelp\u2122 ist eine Marke, alle Rechte vorbehalten.<\/small><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1767683935428 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div style=\"display:flex; justify-content:center; margin:40px 0;\">\n  <div style=\"width:1120px; max-width:100%;\">\n    <div style=\"position:relative; padding-bottom:56.25%; height:0;\">\n      <iframe \n        src=\"https:\/\/www.youtube-nocookie.com\/embed\/OSlbanIPoQQ?si=woKoKeiSUxVt_LGs\"\n        title=\"YouTube videospeler\"\n        style=\"position:absolute; top:0; left:0; width:100%; height:100%;\"\n        frameborder=\"0\"\n        allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\"\n        referrerpolicy=\"strict-origin-when-cross-origin\"\n        allowfullscreen>\n      <\/iframe>\n    <\/div>\n  <\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1767683924617\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"templatera_shortcode\"><style type=\"text\/css\" data-type=\"vc_shortcodes-custom-css\">.vc_custom_1765116274052{margin-top: 0px !important;margin-bottom: 60px !important;background-color: #E3E3E3 !important;}.vc_custom_1765115037096{padding-bottom: 60px !important;}.vc_custom_1765115498022{margin-bottom: 60px !important;}<\/style><div id=\"help\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1765116274052 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1765115037096\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Internationale gids van hulp- en preventiediensten<\/h1>\n<h2 data-start=\"316\" data-end=\"345\"><strong data-start=\"319\" data-end=\"345\">Wereldwijd \/ Internationaal<\/strong><\/h2>\n<ul data-start=\"347\" data-end=\"668\">\n<li data-start=\"347\" data-end=\"497\">\n<p data-start=\"349\" data-end=\"497\"><strong data-start=\"349\" data-end=\"393\">Onrustig verlangen - Online zelfmanagement<\/strong><br data-start=\"393\" data-end=\"396\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"398\" data-end=\"429\">https:\/\/troubled-desire.com\/en\/<\/a><br data-start=\"429\" data-end=\"432\" \/>Programma en ligne d'auto-gestion pour personnes en difficult\u00e9.<\/p>\n<\/li>\n<li data-start=\"499\" data-end=\"668\">\n<p data-start=\"501\" data-end=\"668\"><strong data-start=\"501\" data-end=\"565\">Ondersteuning voor minderjarigen die zich aangetrokken voelen tot jongere kinderen (MAP Resources)<\/strong><br data-start=\"565\" data-end=\"568\" \/><a class=\"decorated-link\" href=\"https:\/\/www.mapresources.info\/support\/minors\" target=\"_new\" rel=\"noopener\" data-start=\"570\" data-end=\"614\">https:\/\/www.mapresources.info\/support\/minors<\/a><br data-start=\"614\" data-end=\"617\" \/>Ressources pour enfants et adolescents concern\u00e9s.<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"670\" data-end=\"673\" \/>\n<h2 data-start=\"675\" data-end=\"708\"><strong data-start=\"678\" data-end=\"708\">Afrika, Midden-Oosten, India<\/strong><\/h2>\n<h3 data-start=\"710\" data-end=\"723\"><strong data-start=\"714\" data-end=\"723\">India<\/strong><\/h3>\n<ul data-start=\"724\" data-end=\"1067\">\n<li data-start=\"724\" data-end=\"803\">\n<p data-start=\"726\" data-end=\"803\">Verlangen: Online-zelfbeheer<br data-start=\"765\" data-end=\"768\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"770\" data-end=\"801\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<li data-start=\"804\" data-end=\"859\">\n<p data-start=\"806\" data-end=\"859\">Beledig India niet<br data-start=\"824\" data-end=\"827\" \/><a class=\"decorated-link\" href=\"https:\/\/dontoffendindia.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"829\" data-end=\"857\">https:\/\/dontoffendindia.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"860\" data-end=\"939\">\n<p data-start=\"862\" data-end=\"939\">Programma voor primaire preventie van seksueel geweld<br data-start=\"911\" data-end=\"914\" \/><a class=\"decorated-link\" href=\"http:\/\/www.pppsv.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"916\" data-end=\"937\">http:\/\/www.pppsv.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"940\" data-end=\"1003\">\n<p data-start=\"942\" data-end=\"1003\">Verontrust verlangen (Hindi)<br data-start=\"965\" data-end=\"968\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/hi\/\" target=\"_new\" rel=\"noopener\" data-start=\"970\" data-end=\"1001\">https:\/\/troubled-desire.com\/hi\/<\/a><\/p>\n<\/li>\n<li data-start=\"1004\" data-end=\"1067\">\n<p data-start=\"1006\" data-end=\"1067\">Verontrust verlangen (Marathi)<br data-start=\"1031\" data-end=\"1034\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/mr\/\" target=\"_new\" rel=\"noopener\" data-start=\"1036\" data-end=\"1067\">https:\/\/troubled-desire.com\/mr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1069\" data-end=\"1072\" \/>\n<h2 data-start=\"1074\" data-end=\"1093\"><strong data-start=\"1077\" data-end=\"1093\">Azi\u00eb-Pacific<\/strong><\/h2>\n<h3 data-start=\"1095\" data-end=\"1112\"><strong data-start=\"1099\" data-end=\"1112\">Australi\u00eb<\/strong><\/h3>\n<ul data-start=\"1113\" data-end=\"1277\">\n<li data-start=\"1113\" data-end=\"1199\">\n<p data-start=\"1115\" data-end=\"1199\">Stop het nu!<br data-start=\"1127\" data-end=\"1130\" \/><a class=\"decorated-link\" href=\"https:\/\/phoenixhouse.com.au\/sexual-violence-and-offering-support\/\" target=\"_new\" rel=\"noopener\" data-start=\"1132\" data-end=\"1197\">https:\/\/phoenixhouse.com.au\/sexual-violence-and-offering-support\/<\/a><\/p>\n<\/li>\n<li data-start=\"1200\" data-end=\"1277\">\n<p data-start=\"1202\" data-end=\"1277\">Verlangen: Online-zelfbeheer<br data-start=\"1241\" data-end=\"1244\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"1246\" data-end=\"1277\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1279\" data-end=\"1292\"><strong data-start=\"1283\" data-end=\"1292\">Japan<\/strong><\/h3>\n<ul data-start=\"1293\" data-end=\"1499\">\n<li data-start=\"1293\" data-end=\"1383\">\n<p data-start=\"1295\" data-end=\"1383\">Vereniging voor het denken over de behandeling van seksuele delinquenten<br data-start=\"1355\" data-end=\"1358\" \/><a class=\"decorated-link\" href=\"http:\/\/www.somec.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"1360\" data-end=\"1381\">http:\/\/www.somec.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"1384\" data-end=\"1499\">\n<p data-start=\"1386\" data-end=\"1499\">Enomoto Kliniek Seksuele Verslavings Groep<br data-start=\"1423\" data-end=\"1426\" \/><a class=\"decorated-link\" href=\"https:\/\/www.enomoto-clinic.jp\/care-list\/sexual-addiction-group-meeting\/\" target=\"_new\" rel=\"noopener\" data-start=\"1428\" data-end=\"1499\">https:\/\/www.enomoto-clinic.jp\/care-list\/sexual-addiction-group-meeting\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1501\" data-end=\"1504\" \/>\n<h2 data-start=\"1506\" data-end=\"1528\"><strong data-start=\"1509\" data-end=\"1528\">Europa &amp; Rusland<\/strong><\/h2>\n<h3 data-start=\"1530\" data-end=\"1545\"><strong data-start=\"1534\" data-end=\"1545\">Oostenrijk<\/strong><\/h3>\n<ul data-start=\"1546\" data-end=\"1647\">\n<li data-start=\"1546\" data-end=\"1592\">\n<p data-start=\"1548\" data-end=\"1592\">M\u00e4nnerberatung<br data-start=\"1562\" data-end=\"1565\" \/><a class=\"decorated-link\" href=\"https:\/\/www.maenner.at\/\" target=\"_new\" rel=\"noopener\" data-start=\"1567\" data-end=\"1590\">https:\/\/www.maenner.at\/<\/a><\/p>\n<\/li>\n<li data-start=\"1593\" data-end=\"1647\">\n<p data-start=\"1595\" data-end=\"1647\">Moedig Beratung<br data-start=\"1611\" data-end=\"1614\" \/><a class=\"decorated-link\" href=\"http:\/\/www.courage-beratung.at\/\" target=\"_new\" rel=\"noopener\" data-start=\"1616\" data-end=\"1647\">http:\/\/www.courage-beratung.at\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1649\" data-end=\"1664\"><strong data-start=\"1653\" data-end=\"1664\">Belgi\u00eb<\/strong><\/h3>\n<ul data-start=\"1665\" data-end=\"1855\">\n<li data-start=\"1665\" data-end=\"1723\">\n<p data-start=\"1667\" data-end=\"1723\">Stop het nu! Brussel<br data-start=\"1689\" data-end=\"1692\" \/><a class=\"decorated-link\" href=\"https:\/\/stopitnow.brussels\/\" target=\"_new\" rel=\"noopener\" data-start=\"1694\" data-end=\"1721\">https:\/\/stopitnow.brussels\/<\/a><\/p>\n<\/li>\n<li data-start=\"1724\" data-end=\"1766\">\n<p data-start=\"1726\" data-end=\"1766\">Stop het nu!<br data-start=\"1738\" data-end=\"1741\" \/><a class=\"decorated-link\" href=\"https:\/\/stopitnow.be\/\" target=\"_new\" rel=\"noopener\" data-start=\"1743\" data-end=\"1764\">https:\/\/stopitnow.be\/<\/a><\/p>\n<\/li>\n<li data-start=\"1767\" data-end=\"1796\">\n<p data-start=\"1769\" data-end=\"1796\">S\u00e9OS<br data-start=\"1773\" data-end=\"1776\" \/><a class=\"decorated-link\" href=\"https:\/\/seos.be\/\" target=\"_new\" rel=\"noopener\" data-start=\"1778\" data-end=\"1794\">https:\/\/seos.be\/<\/a><\/p>\n<\/li>\n<li data-start=\"1797\" data-end=\"1855\">\n<p data-start=\"1799\" data-end=\"1855\">Verontrust verlangen (FR)<br data-start=\"1819\" data-end=\"1822\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"1824\" data-end=\"1855\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1857\" data-end=\"1872\"><strong data-start=\"1861\" data-end=\"1872\">Kroati\u00eb<\/strong><\/h3>\n<ul data-start=\"1873\" data-end=\"1939\">\n<li data-start=\"1873\" data-end=\"1939\">\n<p data-start=\"1875\" data-end=\"1939\">Kliniek voor psihijatriju Vrap\u010de<br data-start=\"1905\" data-end=\"1908\" \/><a class=\"decorated-link\" href=\"http:\/\/bolnica-vrapce.hr\/web\/\" target=\"_new\" rel=\"noopener\" data-start=\"1910\" data-end=\"1939\">http:\/\/bolnica-vrapce.hr\/web\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1941\" data-end=\"1956\"><strong data-start=\"1945\" data-end=\"1956\">Denemarken<\/strong><\/h3>\n<ul data-start=\"1957\" data-end=\"2022\">\n<li data-start=\"1957\" data-end=\"2022\">\n<p data-start=\"1959\" data-end=\"2022\">Bryd Cirklen<br data-start=\"1971\" data-end=\"1974\" \/><a class=\"decorated-link\" href=\"https:\/\/www.psykiatri-regionh.dk\/bryd-cirklen\/\" target=\"_new\" rel=\"noopener\" data-start=\"1976\" data-end=\"2022\">https:\/\/www.psykiatri-regionh.dk\/bryd-cirklen\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2024\" data-end=\"2039\"><strong data-start=\"2028\" data-end=\"2039\">Estland<\/strong><\/h3>\n<ul data-start=\"2040\" data-end=\"2097\">\n<li data-start=\"2040\" data-end=\"2097\">\n<p data-start=\"2042\" data-end=\"2097\">Seksuaalh\u00e4ire n\u00f5uandetelefon<br data-start=\"2070\" data-end=\"2073\" \/><a class=\"decorated-link\" href=\"http:\/\/abikeskused.ee\/\" target=\"_new\" rel=\"noopener\" data-start=\"2075\" data-end=\"2097\">http:\/\/abikeskused.ee\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2099\" data-end=\"2114\"><strong data-start=\"2103\" data-end=\"2114\">Finland<\/strong><\/h3>\n<ul data-start=\"2115\" data-end=\"2195\">\n<li data-start=\"2115\" data-end=\"2162\">\n<p data-start=\"2117\" data-end=\"2162\">Otan Vastuun<br data-start=\"2129\" data-end=\"2132\" \/><a class=\"decorated-link\" href=\"http:\/\/www.otanvastuun.fi\/\" target=\"_new\" rel=\"noopener\" data-start=\"2134\" data-end=\"2160\">http:\/\/www.otanvastuun.fi\/<\/a><\/p>\n<\/li>\n<li data-start=\"2163\" data-end=\"2195\">\n<p data-start=\"2165\" data-end=\"2195\">Sexpo<br data-start=\"2170\" data-end=\"2173\" \/><a class=\"decorated-link\" href=\"http:\/\/www.sexpo.fi\/\" target=\"_new\" rel=\"noopener\" data-start=\"2175\" data-end=\"2195\">http:\/\/www.sexpo.fi\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2197\" data-end=\"2211\"><strong data-start=\"2201\" data-end=\"2211\">Frankrijk<\/strong><\/h3>\n<ul data-start=\"2212\" data-end=\"2476\">\n<li data-start=\"2212\" data-end=\"2337\">\n<p data-start=\"2214\" data-end=\"2337\">Num\u00e9ro STOP (T\u00e9l\u00e9phonique d'Orientation et de Pr\u00e9vention)<br data-start=\"2279\" data-end=\"2282\" \/><a class=\"decorated-link\" href=\"https:\/\/www.ffcriavs.org\/nos-actions\/numero-unique\/\" target=\"_new\" rel=\"noopener\" data-start=\"2284\" data-end=\"2335\">https:\/\/www.ffcriavs.org\/nos-actions\/numero-unique\/<\/a><\/p>\n<\/li>\n<li data-start=\"2338\" data-end=\"2417\">\n<p data-start=\"2340\" data-end=\"2417\">Vereniging L'Ange Bleu<br data-start=\"2363\" data-end=\"2366\" \/><a class=\"decorated-link\" href=\"http:\/\/ange-bleu.com\/fr\/le-reseau-de-lange-bleu\" target=\"_new\" rel=\"noopener\" data-start=\"2368\" data-end=\"2415\">http:\/\/ange-bleu.com\/fr\/le-reseau-de-lange-bleu<\/a><\/p>\n<\/li>\n<li data-start=\"2418\" data-end=\"2476\">\n<p data-start=\"2420\" data-end=\"2476\">Verontrust verlangen (FR)<br data-start=\"2440\" data-end=\"2443\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"2445\" data-end=\"2476\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2478\" data-end=\"2493\"><strong data-start=\"2482\" data-end=\"2493\">Duitsland<\/strong><\/h3>\n<ul data-start=\"2494\" data-end=\"2818\">\n<li data-start=\"2494\" data-end=\"2621\">\n<p data-start=\"2496\" data-end=\"2621\">Kein T\u00e4ter Werden (Niet beledigen)<br data-start=\"2528\" data-end=\"2531\" \/><a class=\"decorated-link\" href=\"https:\/\/www.kein-taeter-werden.de\/\" target=\"_new\" rel=\"noopener\" data-start=\"2533\" data-end=\"2567\">https:\/\/www.kein-taeter-werden.de\/<\/a><br data-start=\"2567\" data-end=\"2570\" \/>- Niet beledigen<br data-start=\"2586\" data-end=\"2589\" \/><a class=\"decorated-link\" href=\"https:\/\/www.dont-offend.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"2591\" data-end=\"2619\">https:\/\/www.dont-offend.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"2622\" data-end=\"2682\">\n<p data-start=\"2624\" data-end=\"2682\">Verontrust verlangen (DE)<br data-start=\"2644\" data-end=\"2647\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/de\/\" target=\"_new\" rel=\"noopener\" data-start=\"2649\" data-end=\"2680\">https:\/\/troubled-desire.com\/de\/<\/a><\/p>\n<\/li>\n<li data-start=\"2683\" data-end=\"2818\">\n<p data-start=\"2685\" data-end=\"2818\">Je bent bang voor hen<br data-start=\"2705\" data-end=\"2708\" \/><a class=\"decorated-link\" href=\"https:\/\/www.du-traeumst-von-ihnen.de\/\" target=\"_new\" rel=\"noopener\" data-start=\"2710\" data-end=\"2747\">https:\/\/www.du-traeumst-von-ihnen.de\/<\/a><br data-start=\"2747\" data-end=\"2750\" \/>- Van ze dromen<br data-start=\"2775\" data-end=\"2778\" \/><a class=\"decorated-link\" href=\"https:\/\/www.just-dreaming-of-them.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"2780\" data-end=\"2818\">https:\/\/www.just-dreaming-of-them.org\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2820\" data-end=\"2835\"><strong data-start=\"2824\" data-end=\"2835\">Hongarije<\/strong><\/h3>\n<ul data-start=\"2836\" data-end=\"2935\">\n<li data-start=\"2836\" data-end=\"2935\">\n<p data-start=\"2838\" data-end=\"2935\">Boedapest Szoci\u00e1lis Forr\u00e1sk\u00f6zpont<br data-start=\"2871\" data-end=\"2874\" \/><a class=\"decorated-link\" href=\"http:\/\/adhat.hu\/szervezet\/budapesti-szocialis-forraskozpont\" target=\"_new\" rel=\"noopener\" data-start=\"2876\" data-end=\"2935\">http:\/\/adhat.hu\/szervezet\/budapesti-szocialis-forraskozpont<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2937\" data-end=\"2952\"><strong data-start=\"2941\" data-end=\"2952\">Ierland<\/strong><\/h3>\n<ul data-start=\"2953\" data-end=\"3135\">\n<li data-start=\"2953\" data-end=\"3025\">\n<p data-start=\"2955\" data-end=\"3025\">Stop het nu! Hulplijn VK &amp; Ierland<br data-start=\"2989\" data-end=\"2992\" \/><a class=\"decorated-link\" href=\"https:\/\/www.stopitnow.org.uk\/\" target=\"_new\" rel=\"noopener\" data-start=\"2994\" data-end=\"3023\">https:\/\/www.stopitnow.org.uk\/<\/a><\/p>\n<\/li>\n<li data-start=\"3026\" data-end=\"3081\">\n<p data-start=\"3028\" data-end=\"3081\">E\u00e9n op vier<br data-start=\"3039\" data-end=\"3042\" \/><a class=\"decorated-link\" href=\"https:\/\/www.oneinfour.ie\/prevention\" target=\"_new\" rel=\"noopener\" data-start=\"3044\" data-end=\"3079\">https:\/\/www.oneinfour.ie\/prevention<\/a><\/p>\n<\/li>\n<li data-start=\"3082\" data-end=\"3135\">\n<p data-start=\"3084\" data-end=\"3135\">Verontrust verlangen<br data-start=\"3099\" data-end=\"3102\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"3104\" data-end=\"3135\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3137\" data-end=\"3150\"><strong data-start=\"3141\" data-end=\"3150\">Itali\u00eb<\/strong><\/h3>\n<ul data-start=\"3151\" data-end=\"3213\">\n<li data-start=\"3151\" data-end=\"3213\">\n<p data-start=\"3153\" data-end=\"3213\">Stop het nu!<br data-start=\"3165\" data-end=\"3168\" \/><a class=\"decorated-link\" href=\"http:\/\/get-help.stopitnow.org.uk\/it\/home-it\" target=\"_new\" rel=\"noopener\" data-start=\"3170\" data-end=\"3213\">http:\/\/get-help.stopitnow.org.uk\/it\/home-it<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3215\" data-end=\"3229\"><strong data-start=\"3219\" data-end=\"3229\">Letland<\/strong><\/h3>\n<ul data-start=\"3230\" data-end=\"3292\">\n<li data-start=\"3230\" data-end=\"3292\">\n<p data-start=\"3232\" data-end=\"3292\">Psihosomatika kl\u012bnikas<br data-start=\"3255\" data-end=\"3258\" \/><a class=\"decorated-link\" href=\"http:\/\/psihosomatika.lv\/kontakti\" target=\"_new\" rel=\"noopener\" data-start=\"3260\" data-end=\"3292\">http:\/\/psihosomatika.lv\/kontakti<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3294\" data-end=\"3312\"><strong data-start=\"3298\" data-end=\"3312\">Luxemburg<\/strong><\/h3>\n<ul data-start=\"3313\" data-end=\"3422\">\n<li data-start=\"3313\" data-end=\"3363\">\n<p data-start=\"3315\" data-end=\"3363\">Hotline tegen geweld<br data-start=\"3335\" data-end=\"3338\" \/><a class=\"decorated-link\" href=\"http:\/\/www.euline.eu\/\" target=\"_new\" rel=\"noopener\" data-start=\"3340\" data-end=\"3361\">http:\/\/www.euline.eu\/<\/a><\/p>\n<\/li>\n<li data-start=\"3364\" data-end=\"3422\">\n<p data-start=\"3366\" data-end=\"3422\">Verontrust verlangen (FR)<br data-start=\"3386\" data-end=\"3389\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"3391\" data-end=\"3422\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3424\" data-end=\"3443\"><strong data-start=\"3428\" data-end=\"3443\">Nederland<\/strong><\/h3>\n<ul data-start=\"3444\" data-end=\"3488\">\n<li data-start=\"3444\" data-end=\"3488\">\n<p data-start=\"3446\" data-end=\"3488\">Stop het nu!<br data-start=\"3458\" data-end=\"3461\" \/><a class=\"decorated-link\" href=\"https:\/\/www.stopitnow.nl\/\" target=\"_new\" rel=\"noopener\" data-start=\"3463\" data-end=\"3488\">https:\/\/www.stopitnow.nl\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3490\" data-end=\"3504\"><strong data-start=\"3494\" data-end=\"3504\">Noorwegen<\/strong><\/h3>\n<ul data-start=\"3505\" data-end=\"3554\">\n<li data-start=\"3505\" data-end=\"3554\">\n<p data-start=\"3507\" data-end=\"3554\">Det finnes hjelp<br data-start=\"3523\" data-end=\"3526\" \/><a class=\"decorated-link\" href=\"https:\/\/detfinneshjelp.no\/\" target=\"_new\" rel=\"noopener\" data-start=\"3528\" data-end=\"3554\">https:\/\/detfinneshjelp.no\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3556\" data-end=\"3572\"><strong data-start=\"3560\" data-end=\"3572\">Portugal<\/strong><\/h3>\n<ul data-start=\"3573\" data-end=\"3626\">\n<li data-start=\"3573\" data-end=\"3626\">\n<p data-start=\"3575\" data-end=\"3626\">Verontrust verlangen<br data-start=\"3590\" data-end=\"3593\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"3595\" data-end=\"3626\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3628\" data-end=\"3644\"><strong data-start=\"3632\" data-end=\"3644\">Sloveni\u00eb<\/strong><\/h3>\n<ul data-start=\"3645\" data-end=\"3790\">\n<li data-start=\"3645\" data-end=\"3790\">\n<p data-start=\"3647\" data-end=\"3790\">Javni zavodi - zdravstveni domovi<br data-start=\"3680\" data-end=\"3683\" \/><a class=\"decorated-link\" href=\"http:\/\/www.mz.gov.si\/si\/pogoste_vsebine_za_javnost\/strokovne_institucije\/javni_zavodi_zdravstveni_domovi\/\" target=\"_new\" rel=\"noopener\" data-start=\"3685\" data-end=\"3790\">http:\/\/www.mz.gov.si\/si\/pogoste_vsebine_za_javnost\/strokovne_institucije\/javni_zavodi_zdravstveni_domovi\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3792\" data-end=\"3805\"><strong data-start=\"3796\" data-end=\"3805\">Spanje<\/strong><\/h3>\n<ul data-start=\"3806\" data-end=\"3944\">\n<li data-start=\"3806\" data-end=\"3843\">\n<p data-start=\"3808\" data-end=\"3843\">PrevenSi<br data-start=\"3816\" data-end=\"3819\" \/><a class=\"decorated-link\" href=\"https:\/\/prevensi.es\/\" target=\"_new\" rel=\"noopener\" data-start=\"3821\" data-end=\"3841\">https:\/\/prevensi.es\/<\/a><\/p>\n<\/li>\n<li data-start=\"3844\" data-end=\"3885\">\n<p data-start=\"3846\" data-end=\"3885\">Engel Blau<br data-start=\"3856\" data-end=\"3859\" \/><a class=\"decorated-link\" href=\"https:\/\/angelblau.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"3861\" data-end=\"3883\">https:\/\/angelblau.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"3886\" data-end=\"3944\">\n<p data-start=\"3888\" data-end=\"3944\">Verontrust verlangen (ES)<br data-start=\"3908\" data-end=\"3911\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/es\/\" target=\"_new\" rel=\"noopener\" data-start=\"3913\" data-end=\"3944\">https:\/\/troubled-desire.com\/es\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3946\" data-end=\"3960\"><strong data-start=\"3950\" data-end=\"3960\">Zweden<\/strong><\/h3>\n<ul data-start=\"3961\" data-end=\"3999\">\n<li data-start=\"3961\" data-end=\"3999\">\n<p data-start=\"3963\" data-end=\"3999\">Preventell<br data-start=\"3973\" data-end=\"3976\" \/><a class=\"decorated-link\" href=\"http:\/\/preventell.se\/\" target=\"_new\" rel=\"noopener\" data-start=\"3978\" data-end=\"3999\">http:\/\/preventell.se\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"4001\" data-end=\"4020\"><strong data-start=\"4005\" data-end=\"4020\">Zwitserland<\/strong><\/h3>\n<ul data-start=\"4021\" data-end=\"4301\">\n<li data-start=\"4021\" data-end=\"4073\">\n<p data-start=\"4023\" data-end=\"4073\">Vereniging DIS NO (FR)<br data-start=\"4046\" data-end=\"4049\" \/><a class=\"decorated-link\" href=\"http:\/\/www.disno.ch\/\" target=\"_new\" rel=\"noopener\" data-start=\"4051\" data-end=\"4071\">http:\/\/www.disno.ch\/<\/a><\/p>\n<\/li>\n<li data-start=\"4074\" data-end=\"4134\">\n<p data-start=\"4076\" data-end=\"4134\">Verontrust verlangen (FR)<br data-start=\"4096\" data-end=\"4099\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"4101\" data-end=\"4132\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<li data-start=\"4135\" data-end=\"4181\">\n<p data-start=\"4137\" data-end=\"4181\">Beforemore (DE)<br data-start=\"4152\" data-end=\"4155\" \/><a class=\"decorated-link\" href=\"https:\/\/beforemore.ch\/\" target=\"_new\" rel=\"noopener\" data-start=\"4157\" data-end=\"4179\">https:\/\/beforemore.ch\/<\/a><\/p>\n<\/li>\n<li data-start=\"4182\" data-end=\"4242\">\n<p data-start=\"4184\" data-end=\"4242\">Verontrust verlangen (DE)<br data-start=\"4204\" data-end=\"4207\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/de\/\" target=\"_new\" rel=\"noopener\" data-start=\"4209\" data-end=\"4240\">https:\/\/troubled-desire.com\/de\/<\/a><\/p>\n<\/li>\n<li data-start=\"4243\" data-end=\"4301\">\n<p data-start=\"4245\" data-end=\"4301\">Verontrust verlangen (IT)<br data-start=\"4265\" data-end=\"4268\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/it\/\" target=\"_new\" rel=\"noopener\" data-start=\"4270\" data-end=\"4301\">https:\/\/troubled-desire.com\/it\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"4303\" data-end=\"4325\"><strong data-start=\"4307\" data-end=\"4325\">Verenigd Koninkrijk<\/strong><\/h3>\n<ul data-start=\"4326\" data-end=\"4489\">\n<li data-start=\"4326\" data-end=\"4398\">\n<p data-start=\"4328\" data-end=\"4398\">Stop het nu! Hulplijn VK &amp; Ierland<br data-start=\"4362\" data-end=\"4365\" \/><a class=\"decorated-link\" href=\"https:\/\/www.stopitnow.org.uk\/\" target=\"_new\" rel=\"noopener\" data-start=\"4367\" data-end=\"4396\">https:\/\/www.stopitnow.org.uk\/<\/a><\/p>\n<\/li>\n<li data-start=\"4399\" data-end=\"4435\">\n<p data-start=\"4401\" data-end=\"4435\">StopSO<br data-start=\"4407\" data-end=\"4410\" \/><a class=\"decorated-link\" href=\"http:\/\/stopso.org.uk\/\" target=\"_new\" rel=\"noopener\" data-start=\"4412\" data-end=\"4433\">http:\/\/stopso.org.uk\/<\/a><\/p>\n<\/li>\n<li data-start=\"4436\" data-end=\"4489\">\n<p data-start=\"4438\" data-end=\"4489\">Verontrust verlangen<br data-start=\"4453\" data-end=\"4456\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"4458\" data-end=\"4489\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"4491\" data-end=\"4494\" \/>\n<h2 data-start=\"4496\" data-end=\"4528\"><strong data-start=\"4499\" data-end=\"4528\">Latijns-Amerika &amp; Cara\u00efben<\/strong><\/h2>\n<h3 data-start=\"4530\" data-end=\"4564\"><strong data-start=\"4534\" data-end=\"4564\">Spaanstalige landen<\/strong><\/h3>\n<ul data-start=\"4565\" data-end=\"4665\">\n<li data-start=\"4565\" data-end=\"4606\">\n<p data-start=\"4567\" data-end=\"4606\">Engel Blau<br data-start=\"4577\" data-end=\"4580\" \/><a class=\"decorated-link\" href=\"https:\/\/angelblau.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"4582\" data-end=\"4604\">https:\/\/angelblau.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"4607\" data-end=\"4665\">\n<p data-start=\"4609\" data-end=\"4665\">Verontrust verlangen (ES)<br data-start=\"4629\" data-end=\"4632\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/es\/\" target=\"_new\" rel=\"noopener\" data-start=\"4634\" data-end=\"4665\">https:\/\/troubled-desire.com\/es\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"4667\" data-end=\"4704\"><strong data-start=\"4671\" data-end=\"4704\">Portugeessprekende landen<\/strong><\/h3>\n<ul data-start=\"4705\" data-end=\"4763\">\n<li data-start=\"4705\" data-end=\"4763\">\n<p data-start=\"4707\" data-end=\"4763\">Verontrust verlangen (PT)<br data-start=\"4727\" data-end=\"4730\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/pt\/\" target=\"_new\" rel=\"noopener\" data-start=\"4732\" data-end=\"4763\">https:\/\/troubled-desire.com\/pt\/<\/a><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"4765\" data-end=\"4768\" \/>\n<h2 data-start=\"4770\" data-end=\"4790\"><strong data-start=\"4773\" data-end=\"4790\">Noord-Amerika<\/strong><\/h2>\n<h3 data-start=\"4792\" data-end=\"4806\"><strong data-start=\"4796\" data-end=\"4806\">Canada<\/strong><\/h3>\n<ul data-start=\"4807\" data-end=\"5023\">\n<li data-start=\"4807\" data-end=\"4862\">\n<p data-start=\"4809\" data-end=\"4862\">Praten voor verandering<br data-start=\"4827\" data-end=\"4830\" \/><a class=\"decorated-link\" href=\"https:\/\/talkingforchange.ca\/\" target=\"_new\" rel=\"noopener\" data-start=\"4832\" data-end=\"4860\">https:\/\/talkingforchange.ca\/<\/a><\/p>\n<\/li>\n<li data-start=\"4863\" data-end=\"4923\">\n<p data-start=\"4865\" data-end=\"4923\">Verontrust verlangen (EN)<br data-start=\"4885\" data-end=\"4888\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/en\/\" target=\"_new\" rel=\"noopener\" data-start=\"4890\" data-end=\"4921\">https:\/\/troubled-desire.com\/en\/<\/a><\/p>\n<\/li>\n<li data-start=\"4924\" data-end=\"4964\">\n<p data-start=\"4926\" data-end=\"4964\">\u00c7a suffit<br data-start=\"4935\" data-end=\"4938\" \/><a class=\"decorated-link\" href=\"https:\/\/casuffit.info\/\" target=\"_new\" rel=\"noopener\" data-start=\"4940\" data-end=\"4962\">https:\/\/casuffit.info\/<\/a><\/p>\n<\/li>\n<li data-start=\"4965\" data-end=\"5023\">\n<p data-start=\"4967\" data-end=\"5023\">Verontrust verlangen (FR)<br data-start=\"4987\" data-end=\"4990\" \/><a class=\"decorated-link\" href=\"https:\/\/troubled-desire.com\/fr\/\" target=\"_new\" rel=\"noopener\" data-start=\"4992\" data-end=\"5023\">https:\/\/troubled-desire.com\/fr\/<\/a><\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"5025\" data-end=\"5036\"><strong data-start=\"5029\" data-end=\"5036\">VS<\/strong><\/h3>\n<ul data-start=\"5037\" data-end=\"5461\">\n<li data-start=\"5037\" data-end=\"5094\">\n<p data-start=\"5039\" data-end=\"5094\">ASAP Belgi\u00eb<br data-start=\"5057\" data-end=\"5060\" \/><a class=\"decorated-link\" href=\"https:\/\/asapinternational.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5062\" data-end=\"5092\">https:\/\/asapinternational.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5095\" data-end=\"5128\">\n<p data-start=\"5097\" data-end=\"5128\">ATSA<br data-start=\"5101\" data-end=\"5104\" \/><a class=\"decorated-link\" href=\"http:\/\/www.atsa.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"5106\" data-end=\"5126\">http:\/\/www.atsa.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"5129\" data-end=\"5167\">\n<p data-start=\"5131\" data-end=\"5167\">B4U-ACT<br data-start=\"5138\" data-end=\"5141\" \/><a class=\"decorated-link\" href=\"http:\/\/www.b4uact.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5143\" data-end=\"5165\">http:\/\/www.b4uact.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5168\" data-end=\"5228\">\n<p data-start=\"5170\" data-end=\"5228\">Prostasie - Zoek hulp<br data-start=\"5190\" data-end=\"5193\" \/><a class=\"decorated-link\" href=\"https:\/\/prostasia.org\/get-help\/\" target=\"_new\" rel=\"noopener\" data-start=\"5195\" data-end=\"5226\">https:\/\/prostasia.org\/get-help\/<\/a><\/p>\n<\/li>\n<li data-start=\"5229\" data-end=\"5294\">\n<p data-start=\"5231\" data-end=\"5294\">Bron voor zedendelinquenten<br data-start=\"5252\" data-end=\"5255\" \/><a class=\"decorated-link\" href=\"http:\/\/www.sexoffenderresource.com\/\" target=\"_new\" rel=\"noopener\" data-start=\"5257\" data-end=\"5292\">http:\/\/www.sexoffenderresource.com\/<\/a><\/p>\n<\/li>\n<li data-start=\"5295\" data-end=\"5341\">\n<p data-start=\"5297\" data-end=\"5341\">Stop het nu!<br data-start=\"5309\" data-end=\"5312\" \/><a class=\"decorated-link\" href=\"http:\/\/www.stopitnow.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5314\" data-end=\"5339\">http:\/\/www.stopitnow.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5342\" data-end=\"5415\">\n<p data-start=\"5344\" data-end=\"5415\">Hulp gezocht (online cursus)<br data-start=\"5371\" data-end=\"5374\" \/><a class=\"decorated-link\" href=\"https:\/\/www.helpwantedprevention.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5376\" data-end=\"5413\">https:\/\/www.helpwantedprevention.org\/<\/a><\/p>\n<\/li>\n<li data-start=\"5416\" data-end=\"5461\">\n<p data-start=\"5418\" data-end=\"5461\">Deugdzame pedofielen<br data-start=\"5437\" data-end=\"5440\" \/><a class=\"decorated-link\" href=\"https:\/\/virped.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"5442\" data-end=\"5461\">https:\/\/virped.org\/<\/a><\/p>\n<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1765115498022\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><small>Wij zijn niet verantwoordelijk voor de inhoud van de websites die op deze pagina worden vermeld.<\/small><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\r\n<\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"\ud83c\udf10 Language \u25be \ud83c\uddec\ud83c\udde7 English \ud83c\uddeb\ud83c\uddf7 Fran\u00e7ais \ud83c\uddf3\ud83c\uddf1 Nederlands \ud83c\udde9\ud83c\uddea Deutsch \ud83c\uddea\ud83c\uddf8 Espa\u00f1ol \ud83c\uddee\ud83c\uddf9 Italiano \ud83c\uddf5\ud83c\uddf9 Portugu\u00eas \ud83c\uddf5\ud83c\uddf1 Polski \ud83c\uddf7\ud83c\uddfa \u0420\u0443\u0441\u0441\u043a\u0438\u0439 \ud83c\uddf9\ud83c\uddf7 T\u00fcrk\u00e7e \ud83c\uddf8\ud83c\udde6 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \ud83c\uddee\ud83c\uddf3 \u0939\u093f\u0928\u094d\u0926\u0940 \ud83c\uddef\ud83c\uddf5 \u65e5\u672c\u8a9e \ud83c\uddf0\ud83c\uddf7 \ud55c\uad6d\uc5b4 \ud83c\udde8\ud83c\uddf3 \u4e2d\u6587 Verst\u00e4ndnis und Unterst\u00fctzung bei der Pr\u00e4vention von sexuellem Kindesmissbrauch Man sucht sich seine Fantasien nicht aus F\u00fchlen Sie sich zu Kindern hingezogen [...]","protected":false},"author":1,"featured_media":0,"parent":1850,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pmpro_default_level":"","footnotes":""},"class_list":["post-2506","page","type-page","status-publish","hentry","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PedoHelp DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pedo.help\/de\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PedoHelp DE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pedo.help\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Vivotis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T08:18:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pedo.help\\\/de\\\/\",\"url\":\"https:\\\/\\\/pedo.help\\\/de\\\/\",\"name\":\"PedoHelp DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vivotis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pedo.help\\\/de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pedo.help\\\/de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ph-ppdonation.webp\",\"datePublished\":\"2026-01-06T07:05:44+00:00\",\"dateModified\":\"2026-01-06T08:18:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pedo.help\\\/de\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pedo.help\\\/de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/pedo.help\\\/de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ph-ppdonation.webp\",\"contentUrl\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ph-ppdonation.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pedo.help\\\/de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vivotis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PedoHelp\",\"item\":\"https:\\\/\\\/pedo.help\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PedoHelp DE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vivotis.com\\\/#website\",\"url\":\"https:\\\/\\\/vivotis.com\\\/\",\"name\":\"Vivotis\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/vivotis.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vivotis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vivotis.com\\\/#organization\",\"name\":\"Vivotis\",\"url\":\"https:\\\/\\\/vivotis.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/vivotis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-brand-000000-m-scaled.png\",\"contentUrl\":\"https:\\\/\\\/vivotis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-brand-000000-m-scaled.png\",\"width\":2560,\"height\":1281,\"caption\":\"Vivotis\"},\"image\":{\"@id\":\"https:\\\/\\\/vivotis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PedoHelp DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pedo.help\/de\/","og_locale":"nl_NL","og_type":"article","og_title":"PedoHelp DE","og_url":"https:\/\/pedo.help\/de\/","og_site_name":"Vivotis","article_modified_time":"2026-01-06T08:18:04+00:00","og_image":[{"url":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"25 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pedo.help\/de\/","url":"https:\/\/pedo.help\/de\/","name":"PedoHelp DE","isPartOf":{"@id":"https:\/\/vivotis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pedo.help\/de\/#primaryimage"},"image":{"@id":"https:\/\/pedo.help\/de\/#primaryimage"},"thumbnailUrl":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp","datePublished":"2026-01-06T07:05:44+00:00","dateModified":"2026-01-06T08:18:04+00:00","breadcrumb":{"@id":"https:\/\/pedo.help\/de\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pedo.help\/de\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/pedo.help\/de\/#primaryimage","url":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp","contentUrl":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/12\/ph-ppdonation.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/pedo.help\/de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vivotis.com\/"},{"@type":"ListItem","position":2,"name":"PedoHelp","item":"https:\/\/pedo.help\/"},{"@type":"ListItem","position":3,"name":"PedoHelp DE"}]},{"@type":"WebSite","@id":"https:\/\/vivotis.com\/#website","url":"https:\/\/vivotis.com\/","name":"Vivotis","description":"","publisher":{"@id":"https:\/\/vivotis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vivotis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/vivotis.com\/#organization","name":"Vivotis","url":"https:\/\/vivotis.com\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/vivotis.com\/#\/schema\/logo\/image\/","url":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/11\/logo-brand-000000-m-scaled.png","contentUrl":"https:\/\/vivotis.com\/wp-content\/uploads\/2025\/11\/logo-brand-000000-m-scaled.png","width":2560,"height":1281,"caption":"Vivotis"},"image":{"@id":"https:\/\/vivotis.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/pages\/2506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/comments?post=2506"}],"version-history":[{"count":0,"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/pages\/2506\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/pages\/1850"}],"wp:attachment":[{"href":"https:\/\/vivotis.com\/nl\/wp-json\/wp\/v2\/media?parent=2506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}